{"id":20996,"date":"2022-12-04T22:22:22","date_gmt":"2022-12-04T21:22:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57.jpg"},"modified":"2022-12-04T22:22:23","modified_gmt":"2022-12-04T21:22:23","slug":"4852317b1ca94a539fd961e212efff57","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/8037-ndrangheta-processo-meta-piovono-assoluzioni\/4852317b1ca94a539fd961e212efff57\/","title":{"rendered":"4852317b1ca94a539fd961e212efff57"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-20996","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/4852317b1ca94a539fd961e212efff57.jpg","filesize":32256,"sizes":{"medium":{"file":"4852317b1ca94a539fd961e212efff57-300x225.jpg","width":300,"height":225,"filesize":15540,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57-300x225.jpg"},"thumbnail":{"file":"4852317b1ca94a539fd961e212efff57-150x150.jpg","width":150,"height":150,"filesize":6481,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57-150x150.jpg"},"full":{"file":"4852317b1ca94a539fd961e212efff57.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":20995,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4852317b1ca94a539fd961e212efff57.jpg","filename":"4852317b1ca94a539fd961e212efff57.jpg","filesize":32256,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":20995,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}