{"id":217076,"date":"2023-11-19T16:36:28","date_gmt":"2023-11-19T15:36:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3.jpg"},"modified":"2023-11-19T16:36:28","modified_gmt":"2023-11-19T15:36:28","slug":"foto3-2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/allarme-ambientale-il-fiume-crocchio-riversa-nel-mare-acqua-nera\/foto3-2\/","title":{"rendered":"foto3"},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-217076","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1024x768.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-768x576.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1536x1152.jpg 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-150x113.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-696x522.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1068x801.jpg 1068w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1920x1440.jpg 1920w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-560x420.jpg 560w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-80x60.jpg 80w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-265x198.jpg 265w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2023\/11\/foto3.jpg","filesize":595744,"sizes":{"medium":{"file":"foto3-300x225.jpg","width":300,"height":225,"filesize":16958,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-300x225.jpg"},"large":{"file":"foto3-1024x768.jpg","width":1024,"height":768,"filesize":192460,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1024x768.jpg"},"thumbnail":{"file":"foto3-150x150.jpg","width":150,"height":150,"filesize":5961,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-150x150.jpg"},"medium_large":{"file":"foto3-768x576.jpg","width":768,"height":576,"filesize":111902,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-768x576.jpg"},"1536x1536":{"file":"foto3-1536x1152.jpg","width":1536,"height":1152,"filesize":399174,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1536x1152.jpg"},"td_150x0":{"file":"foto3-150x113.jpg","width":150,"height":113,"filesize":4793,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-150x113.jpg"},"td_218x150":{"file":"foto3-218x150.jpg","width":218,"height":150,"filesize":8358,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-218x150.jpg"},"td_300x0":{"file":"foto3-300x225.jpg","width":300,"height":225,"filesize":16958,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-300x225.jpg"},"td_324x400":{"file":"foto3-324x400.jpg","width":324,"height":400,"filesize":32492,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-324x400.jpg"},"td_485x360":{"file":"foto3-485x360.jpg","width":485,"height":360,"filesize":43596,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-485x360.jpg"},"td_696x0":{"file":"foto3-696x522.jpg","width":696,"height":522,"filesize":92612,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-696x522.jpg"},"td_1068x0":{"file":"foto3-1068x801.jpg","width":1068,"height":801,"filesize":215011,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1068x801.jpg"},"td_1920x0":{"file":"foto3-1920x1440.jpg","width":1920,"height":1440,"filesize":568243,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1920x1440.jpg"},"td_0x420":{"file":"foto3-560x420.jpg","width":560,"height":420,"filesize":59260,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-560x420.jpg"},"td_80x60":{"file":"foto3-80x60.jpg","width":80,"height":60,"filesize":1700,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-80x60.jpg"},"td_100x70":{"file":"foto3-100x70.jpg","width":100,"height":70,"filesize":2332,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-100x70.jpg"},"td_265x198":{"file":"foto3-265x198.jpg","width":265,"height":198,"filesize":13256,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-265x198.jpg"},"td_324x160":{"file":"foto3-324x160.jpg","width":324,"height":160,"filesize":11482,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-324x160.jpg"},"td_324x235":{"file":"foto3-324x235.jpg","width":324,"height":235,"filesize":19210,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-324x235.jpg"},"td_356x220":{"file":"foto3-356x220.jpg","width":356,"height":220,"filesize":18910,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-356x220.jpg"},"td_356x364":{"file":"foto3-356x364.jpg","width":356,"height":364,"filesize":32964,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-356x364.jpg"},"td_533x261":{"file":"foto3-533x261.jpg","width":533,"height":261,"filesize":30651,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-533x261.jpg"},"td_534x462":{"file":"foto3-534x462.jpg","width":534,"height":462,"filesize":62782,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-534x462.jpg"},"td_696x385":{"file":"foto3-696x385.jpg","width":696,"height":385,"filesize":62426,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-696x385.jpg"},"td_741x486":{"file":"foto3-741x486.jpg","width":741,"height":486,"filesize":89384,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-741x486.jpg"},"td_1068x580":{"file":"foto3-1068x580.jpg","width":1068,"height":580,"filesize":143319,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3-1068x580.jpg"},"full":{"file":"foto3.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":217066,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/11\/foto3.jpg","filename":"foto3.jpg","filesize":595744,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/217076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":217066,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/217066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}