{"id":218089,"date":"2023-12-01T17:46:51","date_gmt":"2023-12-01T16:46:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1.jpg"},"modified":"2023-12-01T17:46:51","modified_gmt":"2023-12-01T16:46:51","slug":"mattarella-occhiuto-1-2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/occhiuto-incontra-mattarella-colloquio-su-opportunita-della-calabria\/mattarella-occhiuto-1-2\/","title":{"rendered":"Mattarella Occhiuto (1)"},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-218089","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-300x186.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-356x220.jpg 356w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":600,"file":"2023\/12\/Mattarella-Occhiuto-1-1.jpg","filesize":704787,"sizes":{"medium":{"file":"Mattarella-Occhiuto-1-1-300x186.jpg","width":300,"height":186,"filesize":22312,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-300x186.jpg"},"thumbnail":{"file":"Mattarella-Occhiuto-1-1-150x150.jpg","width":150,"height":150,"filesize":10374,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-150x150.jpg"},"medium_large":{"file":"Mattarella-Occhiuto-1-1-768x475.jpg","width":768,"height":475,"filesize":104578,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-768x475.jpg"},"td_150x0":{"file":"Mattarella-Occhiuto-1-1-150x93.jpg","width":150,"height":93,"filesize":7257,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-150x93.jpg"},"td_218x150":{"file":"Mattarella-Occhiuto-1-1-218x150.jpg","width":218,"height":150,"filesize":14154,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-218x150.jpg"},"td_300x0":{"file":"Mattarella-Occhiuto-1-1-300x186.jpg","width":300,"height":186,"filesize":22291,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-300x186.jpg"},"td_324x400":{"file":"Mattarella-Occhiuto-1-1-324x400.jpg","width":324,"height":400,"filesize":40666,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-324x400.jpg"},"td_485x360":{"file":"Mattarella-Occhiuto-1-1-485x360.jpg","width":485,"height":360,"filesize":54993,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-485x360.jpg"},"td_696x0":{"file":"Mattarella-Occhiuto-1-1-696x431.jpg","width":696,"height":431,"filesize":88371,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-696x431.jpg"},"td_0x420":{"file":"Mattarella-Occhiuto-1-1-679x420.jpg","width":679,"height":420,"filesize":85187,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-679x420.jpg"},"td_80x60":{"file":"Mattarella-Occhiuto-1-1-80x60.jpg","width":80,"height":60,"filesize":3309,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-80x60.jpg"},"td_100x70":{"file":"Mattarella-Occhiuto-1-1-100x70.jpg","width":100,"height":70,"filesize":4216,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-100x70.jpg"},"td_265x198":{"file":"Mattarella-Occhiuto-1-1-265x198.jpg","width":265,"height":198,"filesize":20735,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-265x198.jpg"},"td_324x160":{"file":"Mattarella-Occhiuto-1-1-324x160.jpg","width":324,"height":160,"filesize":19626,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-324x160.jpg"},"td_324x235":{"file":"Mattarella-Occhiuto-1-1-324x235.jpg","width":324,"height":235,"filesize":28315,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-324x235.jpg"},"td_356x220":{"file":"Mattarella-Occhiuto-1-1-356x220.jpg","width":356,"height":220,"filesize":29523,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-356x220.jpg"},"td_356x364":{"file":"Mattarella-Occhiuto-1-1-356x364.jpg","width":356,"height":364,"filesize":43214,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-356x364.jpg"},"td_533x261":{"file":"Mattarella-Occhiuto-1-1-533x261.jpg","width":533,"height":261,"filesize":44386,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-533x261.jpg"},"td_534x462":{"file":"Mattarella-Occhiuto-1-1-534x462.jpg","width":534,"height":462,"filesize":72773,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-534x462.jpg"},"td_696x385":{"file":"Mattarella-Occhiuto-1-1-696x385.jpg","width":696,"height":385,"filesize":76696,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-696x385.jpg"},"td_741x486":{"file":"Mattarella-Occhiuto-1-1-741x486.jpg","width":741,"height":486,"filesize":101470,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-741x486.jpg"},"td_1068x580":{"file":"Mattarella-Occhiuto-1-1-970x580.jpg","width":970,"height":580,"filesize":159872,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1-970x580.jpg"},"full":{"file":"Mattarella-Occhiuto-1-1.jpg","width":970,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":218079,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/12\/Mattarella-Occhiuto-1-1.jpg","filename":"Mattarella-Occhiuto-1-1.jpg","filesize":704787,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/218089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":218079,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/218079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}