{"id":22600,"date":"2022-12-04T22:54:53","date_gmt":"2022-12-04T21:54:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg"},"modified":"2022-12-04T22:54:54","modified_gmt":"2022-12-04T21:54:54","slug":"fa90cf202eb21d9e331e30fc150ca613","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/8879-emergenza-rifiuti-a-castrolibero-assemblea-pubblica-per-uscire-dalla-crisi\/fa90cf202eb21d9e331e30fc150ca613\/","title":{"rendered":"fa90cf202eb21d9e331e30fc150ca613"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-22600","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg","filesize":19027,"sizes":{"medium":{"file":"fa90cf202eb21d9e331e30fc150ca613-300x225.jpg","width":300,"height":225,"filesize":10914,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613-300x225.jpg"},"thumbnail":{"file":"fa90cf202eb21d9e331e30fc150ca613-150x150.jpg","width":150,"height":150,"filesize":5243,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613-150x150.jpg"},"full":{"file":"fa90cf202eb21d9e331e30fc150ca613.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":22599,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/fa90cf202eb21d9e331e30fc150ca613.jpg","filename":"fa90cf202eb21d9e331e30fc150ca613.jpg","filesize":19027,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":22599,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}