{"id":22710,"date":"2022-12-04T22:57:09","date_gmt":"2022-12-04T21:57:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg"},"modified":"2022-12-04T22:57:09","modified_gmt":"2022-12-04T21:57:09","slug":"d23f280ffd2608eb1dd978a8a9df6749","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/8935-due-ex-coniugi-e-il-terzo-incomodo-si-scatena-la-rissa-in-via-panebianco\/d23f280ffd2608eb1dd978a8a9df6749\/","title":{"rendered":"d23f280ffd2608eb1dd978a8a9df6749"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-22710","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":259,"height":194,"file":"2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg","filesize":11177,"sizes":{"thumbnail":{"file":"d23f280ffd2608eb1dd978a8a9df6749-150x150.jpg","width":150,"height":150,"filesize":6551,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749-150x150.jpg"},"full":{"file":"d23f280ffd2608eb1dd978a8a9df6749.jpg","width":259,"height":194,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":22709,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/d23f280ffd2608eb1dd978a8a9df6749.jpg","filename":"d23f280ffd2608eb1dd978a8a9df6749.jpg","filesize":11177,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":22709,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}