{"id":228351,"date":"2024-04-22T00:29:46","date_gmt":"2024-04-21T22:29:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18.jpg"},"modified":"2024-04-22T00:29:46","modified_gmt":"2024-04-21T22:29:46","slug":"parcobenessere_18","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/parcobenessere_18\/","title":{"rendered":"parcobenessere_18"},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-228351","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-768x512.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-696x464.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-630x420.jpg 630w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":640,"file":"2024\/04\/parcobenessere_18.jpg","filesize":501657,"sizes":{"medium":{"file":"parcobenessere_18-300x200.jpg","width":300,"height":200,"filesize":40213,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-300x200.jpg"},"thumbnail":{"file":"parcobenessere_18-150x150.jpg","width":150,"height":150,"filesize":32854,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-150x150.jpg"},"medium_large":{"file":"parcobenessere_18-768x512.jpg","width":768,"height":512,"filesize":94153,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-768x512.jpg"},"td_150x0":{"file":"parcobenessere_18-150x100.jpg","width":150,"height":100,"filesize":30973,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-150x100.jpg"},"td_218x150":{"file":"parcobenessere_18-218x150.jpg","width":218,"height":150,"filesize":34978,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-218x150.jpg"},"td_300x0":{"file":"parcobenessere_18-300x200.jpg","width":300,"height":200,"filesize":40213,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-300x200.jpg"},"td_324x400":{"file":"parcobenessere_18-324x400.jpg","width":324,"height":400,"filesize":53224,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-324x400.jpg"},"td_485x360":{"file":"parcobenessere_18-485x360.jpg","width":485,"height":360,"filesize":61004,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-485x360.jpg"},"td_696x0":{"file":"parcobenessere_18-696x464.jpg","width":696,"height":464,"filesize":84176,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-696x464.jpg"},"td_0x420":{"file":"parcobenessere_18-630x420.jpg","width":630,"height":420,"filesize":75964,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-630x420.jpg"},"td_80x60":{"file":"parcobenessere_18-80x60.jpg","width":80,"height":60,"filesize":28281,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-80x60.jpg"},"td_100x70":{"file":"parcobenessere_18-100x70.jpg","width":100,"height":70,"filesize":29015,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-100x70.jpg"},"td_265x198":{"file":"parcobenessere_18-265x198.jpg","width":265,"height":198,"filesize":38963,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-265x198.jpg"},"td_324x160":{"file":"parcobenessere_18-324x160.jpg","width":324,"height":160,"filesize":38809,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-324x160.jpg"},"td_324x235":{"file":"parcobenessere_18-324x235.jpg","width":324,"height":235,"filesize":43757,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-324x235.jpg"},"td_356x220":{"file":"parcobenessere_18-356x220.jpg","width":356,"height":220,"filesize":44173,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-356x220.jpg"},"td_356x364":{"file":"parcobenessere_18-356x364.jpg","width":356,"height":364,"filesize":53491,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-356x364.jpg"},"td_533x261":{"file":"parcobenessere_18-533x261.jpg","width":533,"height":261,"filesize":54502,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-533x261.jpg"},"td_534x462":{"file":"parcobenessere_18-534x462.jpg","width":534,"height":462,"filesize":72499,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-534x462.jpg"},"td_696x385":{"file":"parcobenessere_18-696x385.jpg","width":696,"height":385,"filesize":74709,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-696x385.jpg"},"td_741x486":{"file":"parcobenessere_18-741x486.jpg","width":741,"height":486,"filesize":90146,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-741x486.jpg"},"td_1068x580":{"file":"parcobenessere_18-960x580.jpg","width":960,"height":580,"filesize":122403,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18-960x580.jpg"},"full":{"file":"parcobenessere_18.jpg","width":960,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18.jpg"}},"image_meta":{"aperture":"4","credit":"...foto francescogreco...","camera":"Canon EOS 7D","caption":"","created_timestamp":"1713722146","copyright":"...foto francescogreco...","focal_length":"58","iso":"3200","shutter_speed":"0.0008","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/parcobenessere_18.jpg","filename":"parcobenessere_18.jpg","filesize":501657,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/228351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/34"}]}}