{"id":23356,"date":"2022-12-04T23:10:10","date_gmt":"2022-12-04T22:10:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg"},"modified":"2022-12-04T23:10:10","modified_gmt":"2022-12-04T22:10:10","slug":"57f80a6fd374f2ceb4f660a3cbdd7d2e","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/9271-la-societa-acque-potabili-spa-chiude-i-rubinetti-di-200-rendesi\/57f80a6fd374f2ceb4f660a3cbdd7d2e\/","title":{"rendered":"57f80a6fd374f2ceb4f660a3cbdd7d2e"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-23356","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg","filesize":17784,"sizes":{"medium":{"file":"57f80a6fd374f2ceb4f660a3cbdd7d2e-300x225.jpg","width":300,"height":225,"filesize":9673,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e-300x225.jpg"},"thumbnail":{"file":"57f80a6fd374f2ceb4f660a3cbdd7d2e-150x150.jpg","width":150,"height":150,"filesize":4560,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e-150x150.jpg"},"full":{"file":"57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":23355,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg","filename":"57f80a6fd374f2ceb4f660a3cbdd7d2e.jpg","filesize":17784,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":23355,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}