{"id":23464,"date":"2022-12-04T23:12:16","date_gmt":"2022-12-04T22:12:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg"},"modified":"2022-12-04T23:12:16","modified_gmt":"2022-12-04T22:12:16","slug":"90b4e7e61d597632f0ee625ca5c3c0b3","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/9327-comunicazione-anas-su-un-nuovo-senso-unico-alternato\/90b4e7e61d597632f0ee625ca5c3c0b3\/","title":{"rendered":"90b4e7e61d597632f0ee625ca5c3c0b3"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-23464","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg","filesize":16576,"sizes":{"medium":{"file":"90b4e7e61d597632f0ee625ca5c3c0b3-300x225.jpg","width":300,"height":225,"filesize":5794,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3-300x225.jpg"},"thumbnail":{"file":"90b4e7e61d597632f0ee625ca5c3c0b3-150x150.jpg","width":150,"height":150,"filesize":3194,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3-150x150.jpg"},"full":{"file":"90b4e7e61d597632f0ee625ca5c3c0b3.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":23463,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/90b4e7e61d597632f0ee625ca5c3c0b3.jpg","filename":"90b4e7e61d597632f0ee625ca5c3c0b3.jpg","filesize":16576,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":23463,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}