{"id":235383,"date":"2024-07-18T12:33:10","date_gmt":"2024-07-18T10:33:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1.jpg"},"modified":"2024-07-18T12:33:19","modified_gmt":"2024-07-18T10:33:19","slug":"incidente-a2-eboli-morti2-2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/terribile-schianto-sulla-a2-a-eboli-due-morti-e-due-feriti-gravi-coinvolti-7-mezzi-e-un-camion\/incidente-a2-eboli-morti2-2\/","title":{"rendered":"incidente A2 Eboli morti2"},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-235383","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-300x187.jpg\" class=\"attachment-medium size-medium\" alt=\"incidente A2 Eboli morti2\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-300x187.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-768x479.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-673x420.jpg 673w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-150x94.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-696x434.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"incidente A2 Eboli morti2","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":605,"file":"2024\/07\/incidente-A2-Eboli-morti2-1.jpg","filesize":115922,"sizes":{"medium":{"file":"incidente-A2-Eboli-morti2-1-300x187.jpg","width":300,"height":187,"filesize":24732,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-300x187.jpg"},"thumbnail":{"file":"incidente-A2-Eboli-morti2-1-150x150.jpg","width":150,"height":150,"filesize":16672,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-150x150.jpg"},"medium_large":{"file":"incidente-A2-Eboli-morti2-1-768x479.jpg","width":768,"height":479,"filesize":74949,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-768x479.jpg"},"td_0x420":{"file":"incidente-A2-Eboli-morti2-1-673x420.jpg","width":673,"height":420,"filesize":63641,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-673x420.jpg"},"td_80x60":{"file":"incidente-A2-Eboli-morti2-1-80x60.jpg","width":80,"height":60,"filesize":12857,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-80x60.jpg"},"td_150x0":{"file":"incidente-A2-Eboli-morti2-1-150x94.jpg","width":150,"height":94,"filesize":15366,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-150x94.jpg"},"td_218x150":{"file":"incidente-A2-Eboli-morti2-1-218x150.jpg","width":218,"height":150,"filesize":19514,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-218x150.jpg"},"td_300x0":{"file":"incidente-A2-Eboli-morti2-1-300x187.jpg","width":300,"height":187,"filesize":24732,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-300x187.jpg"},"td_324x400":{"file":"incidente-A2-Eboli-morti2-1-324x400.jpg","width":324,"height":400,"filesize":34104,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-324x400.jpg"},"td_485x360":{"file":"incidente-A2-Eboli-morti2-1-485x360.jpg","width":485,"height":360,"filesize":45157,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-485x360.jpg"},"td_696x0":{"file":"incidente-A2-Eboli-morti2-1-696x434.jpg","width":696,"height":434,"filesize":66461,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-696x434.jpg"},"td_100x70":{"file":"incidente-A2-Eboli-morti2-1-100x70.jpg","width":100,"height":70,"filesize":13517,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-100x70.jpg"},"td_265x198":{"file":"incidente-A2-Eboli-morti2-1-265x198.jpg","width":265,"height":198,"filesize":23645,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-265x198.jpg"},"td_324x160":{"file":"incidente-A2-Eboli-morti2-1-324x160.jpg","width":324,"height":160,"filesize":23647,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-324x160.jpg"},"td_324x235":{"file":"incidente-A2-Eboli-morti2-1-324x235.jpg","width":324,"height":235,"filesize":28450,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-324x235.jpg"},"td_356x220":{"file":"incidente-A2-Eboli-morti2-1-356x220.jpg","width":356,"height":220,"filesize":29300,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-356x220.jpg"},"td_356x364":{"file":"incidente-A2-Eboli-morti2-1-356x364.jpg","width":356,"height":364,"filesize":35837,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-356x364.jpg"},"td_533x261":{"file":"incidente-A2-Eboli-morti2-1-533x261.jpg","width":533,"height":261,"filesize":38839,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-533x261.jpg"},"td_534x462":{"file":"incidente-A2-Eboli-morti2-1-534x462.jpg","width":534,"height":462,"filesize":54056,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-534x462.jpg"},"td_696x385":{"file":"incidente-A2-Eboli-morti2-1-696x385.jpg","width":696,"height":385,"filesize":58996,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-696x385.jpg"},"td_741x486":{"file":"incidente-A2-Eboli-morti2-1-741x486.jpg","width":741,"height":486,"filesize":73254,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-741x486.jpg"},"td_1068x580":{"file":"incidente-A2-Eboli-morti2-1-970x580.jpg","width":970,"height":580,"filesize":108000,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1-970x580.jpg"},"full":{"file":"incidente-A2-Eboli-morti2-1.jpg","width":970,"height":605,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":235375,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/07\/incidente-A2-Eboli-morti2-1.jpg","filename":"incidente-A2-Eboli-morti2-1.jpg","filesize":115922,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":235375,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}