{"id":248171,"date":"2025-01-01T11:13:21","date_gmt":"2025-01-01T10:13:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3.jpg"},"modified":"2025-01-01T11:13:21","modified_gmt":"2025-01-01T10:13:21","slug":"j-ax3","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/rocco-hunt-e-j-ax-tiromancino-e-fred-de-palma-piazze-strapiene-anche-a-cassano-acri-e-corigliano-rossano\/j-ax3\/","title":{"rendered":"J-Ax3"},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-248171","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-768x512.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-630x420.jpg 630w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-696x464.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":647,"file":"2025\/01\/J-Ax3.jpg","filesize":115631,"sizes":{"medium":{"file":"J-Ax3-300x200.jpg","width":300,"height":200,"filesize":26570,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-300x200.jpg"},"thumbnail":{"file":"J-Ax3-150x150.jpg","width":150,"height":150,"filesize":18091,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-150x150.jpg"},"medium_large":{"file":"J-Ax3-768x512.jpg","width":768,"height":512,"filesize":73917,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-768x512.jpg"},"td_0x420":{"file":"J-Ax3-630x420.jpg","width":630,"height":420,"filesize":58353,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-630x420.jpg"},"td_80x60":{"file":"J-Ax3-80x60.jpg","width":80,"height":60,"filesize":13084,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-80x60.jpg"},"td_150x0":{"file":"J-Ax3-150x100.jpg","width":150,"height":100,"filesize":16384,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-150x100.jpg"},"td_218x150":{"file":"J-Ax3-218x150.jpg","width":218,"height":150,"filesize":20948,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-218x150.jpg"},"td_300x0":{"file":"J-Ax3-300x200.jpg","width":300,"height":200,"filesize":26570,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-300x200.jpg"},"td_324x400":{"file":"J-Ax3-324x400.jpg","width":324,"height":400,"filesize":36885,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-324x400.jpg"},"td_485x360":{"file":"J-Ax3-485x360.jpg","width":485,"height":360,"filesize":44918,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-485x360.jpg"},"td_696x0":{"file":"J-Ax3-696x464.jpg","width":696,"height":464,"filesize":65438,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-696x464.jpg"},"td_100x70":{"file":"J-Ax3-100x70.jpg","width":100,"height":70,"filesize":13945,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-100x70.jpg"},"td_265x198":{"file":"J-Ax3-265x198.jpg","width":265,"height":198,"filesize":24931,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-265x198.jpg"},"td_324x160":{"file":"J-Ax3-324x160.jpg","width":324,"height":160,"filesize":23778,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-324x160.jpg"},"td_324x235":{"file":"J-Ax3-324x235.jpg","width":324,"height":235,"filesize":29599,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-324x235.jpg"},"td_356x220":{"file":"J-Ax3-356x220.jpg","width":356,"height":220,"filesize":29867,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-356x220.jpg"},"td_356x364":{"file":"J-Ax3-356x364.jpg","width":356,"height":364,"filesize":37750,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-356x364.jpg"},"td_533x261":{"file":"J-Ax3-533x261.jpg","width":533,"height":261,"filesize":37642,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-533x261.jpg"},"td_534x462":{"file":"J-Ax3-534x462.jpg","width":534,"height":462,"filesize":54276,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-534x462.jpg"},"td_696x385":{"file":"J-Ax3-696x385.jpg","width":696,"height":385,"filesize":56310,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-696x385.jpg"},"td_741x486":{"file":"J-Ax3-741x486.jpg","width":741,"height":486,"filesize":69822,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-741x486.jpg"},"td_1068x580":{"file":"J-Ax3-970x580.jpg","width":970,"height":580,"filesize":99234,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3-970x580.jpg"},"full":{"file":"J-Ax3.jpg","width":970,"height":647,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":248153,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/01\/J-Ax3.jpg","filename":"J-Ax3.jpg","filesize":115631,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":248153,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/248153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}