{"id":25510,"date":"2022-12-04T23:53:19","date_gmt":"2022-12-04T22:53:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg"},"modified":"2022-12-04T23:53:19","modified_gmt":"2022-12-04T22:53:19","slug":"a75037c6d98a6c3cb96fc09bf20d5f4e","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/10380-giornata-conclusiva-di-ti-presento-campus-non-delude-le-aspettative\/a75037c6d98a6c3cb96fc09bf20d5f4e\/","title":{"rendered":"a75037c6d98a6c3cb96fc09bf20d5f4e"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-25510","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg","filesize":30943,"sizes":{"medium":{"file":"a75037c6d98a6c3cb96fc09bf20d5f4e-300x227.jpg","width":300,"height":227,"filesize":19468,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e-300x227.jpg"},"thumbnail":{"file":"a75037c6d98a6c3cb96fc09bf20d5f4e-150x150.jpg","width":150,"height":150,"filesize":7539,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e-150x150.jpg"},"full":{"file":"a75037c6d98a6c3cb96fc09bf20d5f4e.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25509,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a75037c6d98a6c3cb96fc09bf20d5f4e.jpg","filename":"a75037c6d98a6c3cb96fc09bf20d5f4e.jpg","filesize":30943,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/25510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25509,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/25509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}