{"id":26174,"date":"2022-12-05T00:06:48","date_gmt":"2022-12-04T23:06:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg"},"modified":"2022-12-05T00:06:48","modified_gmt":"2022-12-04T23:06:48","slug":"e89866e8460413b3e825fe0ad45ff3bb","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/10723-universita-e-baroni-indispensabili-concorsi-pubblici-senza-corruzione\/e89866e8460413b3e825fe0ad45ff3bb\/","title":{"rendered":"e89866e8460413b3e825fe0ad45ff3bb"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-26174","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg","filesize":31916,"sizes":{"medium":{"file":"e89866e8460413b3e825fe0ad45ff3bb-300x227.jpg","width":300,"height":227,"filesize":23509,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb-300x227.jpg"},"thumbnail":{"file":"e89866e8460413b3e825fe0ad45ff3bb-150x150.jpg","width":150,"height":150,"filesize":9141,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb-150x150.jpg"},"full":{"file":"e89866e8460413b3e825fe0ad45ff3bb.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":26173,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/e89866e8460413b3e825fe0ad45ff3bb.jpg","filename":"e89866e8460413b3e825fe0ad45ff3bb.jpg","filesize":31916,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":26173,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}