{"id":263351,"date":"2025-07-04T10:44:56","date_gmt":"2025-07-04T08:44:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso.jpg"},"modified":"2025-07-04T10:44:56","modified_gmt":"2025-07-04T08:44:56","slug":"auto-di-lusso-3","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/operazione-vortex-maxi-frode-1-000-auto-di-lusso-due-arresti-e-sequestro-35-milioni\/auto-di-lusso-3\/","title":{"rendered":"Auto di lusso"},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-263351","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"189\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-300x189.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-300x189.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-768x484.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-667x420.jpg 667w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-150x94.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-696x438.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":611,"file":"2025\/07\/Auto-di-lusso.jpg","filesize":295205,"sizes":{"medium":{"file":"Auto-di-lusso-300x189.jpg","width":300,"height":189,"filesize":34730,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-300x189.jpg"},"thumbnail":{"file":"Auto-di-lusso-150x150.jpg","width":150,"height":150,"filesize":28721,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-150x150.jpg"},"medium_large":{"file":"Auto-di-lusso-768x484.jpg","width":768,"height":484,"filesize":67312,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-768x484.jpg"},"td_0x420":{"file":"Auto-di-lusso-667x420.jpg","width":667,"height":420,"filesize":59599,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-667x420.jpg"},"td_80x60":{"file":"Auto-di-lusso-80x60.jpg","width":80,"height":60,"filesize":24836,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-80x60.jpg"},"td_150x0":{"file":"Auto-di-lusso-150x94.jpg","width":150,"height":94,"filesize":27032,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-150x94.jpg"},"td_218x150":{"file":"Auto-di-lusso-218x150.jpg","width":218,"height":150,"filesize":30845,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-218x150.jpg"},"td_300x0":{"file":"Auto-di-lusso-300x189.jpg","width":300,"height":189,"filesize":34730,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-300x189.jpg"},"td_324x400":{"file":"Auto-di-lusso-324x400.jpg","width":324,"height":400,"filesize":42285,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-324x400.jpg"},"td_485x360":{"file":"Auto-di-lusso-485x360.jpg","width":485,"height":360,"filesize":49392,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-485x360.jpg"},"td_696x0":{"file":"Auto-di-lusso-696x438.jpg","width":696,"height":438,"filesize":61383,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-696x438.jpg"},"td_100x70":{"file":"Auto-di-lusso-100x70.jpg","width":100,"height":70,"filesize":25351,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-100x70.jpg"},"td_265x198":{"file":"Auto-di-lusso-265x198.jpg","width":265,"height":198,"filesize":34229,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-265x198.jpg"},"td_324x160":{"file":"Auto-di-lusso-324x160.jpg","width":324,"height":160,"filesize":33465,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-324x160.jpg"},"td_324x235":{"file":"Auto-di-lusso-324x235.jpg","width":324,"height":235,"filesize":37805,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-324x235.jpg"},"td_356x220":{"file":"Auto-di-lusso-356x220.jpg","width":356,"height":220,"filesize":37921,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-356x220.jpg"},"td_356x364":{"file":"Auto-di-lusso-356x364.jpg","width":356,"height":364,"filesize":43367,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-356x364.jpg"},"td_533x261":{"file":"Auto-di-lusso-533x261.jpg","width":533,"height":261,"filesize":44349,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-533x261.jpg"},"td_534x462":{"file":"Auto-di-lusso-534x462.jpg","width":534,"height":462,"filesize":55686,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-534x462.jpg"},"td_696x385":{"file":"Auto-di-lusso-696x385.jpg","width":696,"height":385,"filesize":56936,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-696x385.jpg"},"td_741x486":{"file":"Auto-di-lusso-741x486.jpg","width":741,"height":486,"filesize":66383,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-741x486.jpg"},"td_1068x580":{"file":"Auto-di-lusso-970x580.jpg","width":970,"height":580,"filesize":82163,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso-970x580.jpg"},"full":{"file":"Auto-di-lusso.jpg","width":970,"height":611,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":263350,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Auto-di-lusso.jpg","filename":"Auto-di-lusso.jpg","filesize":295205,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/263351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":263350,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/263350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}