{"id":27859,"date":"2022-12-05T00:44:35","date_gmt":"2022-12-04T23:44:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg"},"modified":"2022-12-05T00:44:35","modified_gmt":"2022-12-04T23:44:35","slug":"a40a392b1e89ecdebf3667e19f1338c4","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/11591-incidente-stradale-nel-reggino-una-vittima-e-due-feriti\/a40a392b1e89ecdebf3667e19f1338c4\/","title":{"rendered":"a40a392b1e89ecdebf3667e19f1338c4"},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-27859","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg","filesize":30160,"sizes":{"medium":{"file":"a40a392b1e89ecdebf3667e19f1338c4-300x227.jpg","width":300,"height":227,"filesize":15930,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4-300x227.jpg"},"thumbnail":{"file":"a40a392b1e89ecdebf3667e19f1338c4-150x150.jpg","width":150,"height":150,"filesize":6198,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4-150x150.jpg"},"full":{"file":"a40a392b1e89ecdebf3667e19f1338c4.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":27858,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/a40a392b1e89ecdebf3667e19f1338c4.jpg","filename":"a40a392b1e89ecdebf3667e19f1338c4.jpg","filesize":30160,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":27858,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}