{"id":280069,"date":"2026-01-06T13:18:39","date_gmt":"2026-01-06T12:18:39","guid":{"rendered":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello.jpg"},"modified":"2026-01-06T13:19:27","modified_gmt":"2026-01-06T12:19:27","slug":"antonio-iannello","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/colpi-pistola-auto-presidente-consiglio-vibo\/antonio-iannello\/","title":{"rendered":"Antonio Iannello"},"author":90,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-280069","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-300x186.jpg\" class=\"attachment-medium size-medium\" alt=\"colpi Antonio Iannello\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"colpi Antonio Iannello","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":600,"file":"2026\/01\/Antonio-Iannello.jpg","filesize":45239,"sizes":{"medium":{"file":"Antonio-Iannello-300x186.jpg","width":300,"height":186,"filesize":8980,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-300x186.jpg"},"thumbnail":{"file":"Antonio-Iannello-150x150.jpg","width":150,"height":150,"filesize":4913,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-150x150.jpg"},"medium_large":{"file":"Antonio-Iannello-768x475.jpg","width":768,"height":475,"filesize":40943,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-768x475.jpg"},"mvp-port-thumb":{"file":"Antonio-Iannello-560x600.jpg","width":560,"height":600,"filesize":36518,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-560x600.jpg"},"mvp-large-thumb":{"file":"Antonio-Iannello-590x354.jpg","width":590,"height":354,"filesize":26509,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-590x354.jpg"},"mvp-mid-thumb":{"file":"Antonio-Iannello-400x240.jpg","width":400,"height":240,"filesize":13611,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-400x240.jpg"},"mvp-small-thumb":{"file":"Antonio-Iannello-80x80.jpg","width":80,"height":80,"filesize":2287,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello-80x80.jpg"},"full":{"file":"Antonio-Iannello.jpg","width":970,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":280064,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Antonio-Iannello.jpg","filename":"Antonio-Iannello.jpg","filesize":45239,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/280069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":280064,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/280064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}