{"id":28320,"date":"2022-12-05T00:54:43","date_gmt":"2022-12-04T23:54:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg"},"modified":"2022-12-05T00:54:44","modified_gmt":"2022-12-04T23:54:44","slug":"92053c0004d893ef36690d2a9ee3676b","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/11828-incidente-stradale-nel-crotonese-due-le-auto-coinvolte\/92053c0004d893ef36690d2a9ee3676b\/","title":{"rendered":"92053c0004d893ef36690d2a9ee3676b"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-28320","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg","filesize":21306,"sizes":{"medium":{"file":"92053c0004d893ef36690d2a9ee3676b-300x227.jpg","width":300,"height":227,"filesize":13737,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b-300x227.jpg"},"thumbnail":{"file":"92053c0004d893ef36690d2a9ee3676b-150x150.jpg","width":150,"height":150,"filesize":5782,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b-150x150.jpg"},"full":{"file":"92053c0004d893ef36690d2a9ee3676b.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":28319,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/92053c0004d893ef36690d2a9ee3676b.jpg","filename":"92053c0004d893ef36690d2a9ee3676b.jpg","filesize":21306,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":28319,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}