{"id":284077,"date":"2026-02-15T13:00:04","date_gmt":"2026-02-15T12:00:04","guid":{"rendered":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05.jpg"},"modified":"2026-02-15T21:00:12","modified_gmt":"2026-02-15T20:00:12","slug":"san-lucido-lungomare-cede-05","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/allarme-mareggiate-lungomare-san-lucido\/san-lucido-lungomare-cede-05\/","title":{"rendered":"san lucido lungomare cede 05"},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-284077","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-300x186.jpg\" class=\"attachment-medium size-medium\" alt=\"Maltempo, Andiloro: &quot;nuova pianificazione territoriale contro il rischio idrogeologico\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Maltempo, Andiloro: \"nuova pianificazione territoriale contro il rischio idrogeologico","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":600,"file":"2026\/02\/san-lucido-lungomare-cede-05.jpg","filesize":64786,"sizes":{"medium":{"file":"san-lucido-lungomare-cede-05-300x186.jpg","width":300,"height":186,"filesize":12215,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-300x186.jpg"},"thumbnail":{"file":"san-lucido-lungomare-cede-05-150x150.jpg","width":150,"height":150,"filesize":5093,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-150x150.jpg"},"medium_large":{"file":"san-lucido-lungomare-cede-05-768x475.jpg","width":768,"height":475,"filesize":68757,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-768x475.jpg"},"mvp-port-thumb":{"file":"san-lucido-lungomare-cede-05-560x600.jpg","width":560,"height":600,"filesize":55945,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-560x600.jpg"},"mvp-large-thumb":{"file":"san-lucido-lungomare-cede-05-590x354.jpg","width":590,"height":354,"filesize":41739,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-590x354.jpg"},"mvp-mid-thumb":{"file":"san-lucido-lungomare-cede-05-400x240.jpg","width":400,"height":240,"filesize":19730,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-400x240.jpg"},"mvp-small-thumb":{"file":"san-lucido-lungomare-cede-05-80x80.jpg","width":80,"height":80,"filesize":2098,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05-80x80.jpg"},"full":{"file":"san-lucido-lungomare-cede-05.jpg","width":970,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":284072,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/san-lucido-lungomare-cede-05.jpg","filename":"san-lucido-lungomare-cede-05.jpg","filesize":64786,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/284077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":284072,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/284072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}