{"id":284746,"date":"2026-02-21T15:25:18","date_gmt":"2026-02-21T14:25:18","guid":{"rendered":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2.jpg"},"modified":"2026-02-21T15:25:18","modified_gmt":"2026-02-21T14:25:18","slug":"agrisolare-2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/campotenese-eccellenza-gusto-sostenibilita\/agrisolare-2\/","title":{"rendered":"Agrisolare 2"},"author":90,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-284746","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-300x186.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":970,"height":600,"file":"2026\/02\/Agrisolare-2.jpg","filesize":59826,"sizes":{"medium":{"file":"Agrisolare-2-300x186.jpg","width":300,"height":186,"filesize":14460,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-300x186.jpg"},"thumbnail":{"file":"Agrisolare-2-150x150.jpg","width":150,"height":150,"filesize":7311,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-150x150.jpg"},"medium_large":{"file":"Agrisolare-2-768x475.jpg","width":768,"height":475,"filesize":65350,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-768x475.jpg"},"mvp-port-thumb":{"file":"Agrisolare-2-560x600.jpg","width":560,"height":600,"filesize":62128,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-560x600.jpg"},"mvp-large-thumb":{"file":"Agrisolare-2-590x354.jpg","width":590,"height":354,"filesize":42111,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-590x354.jpg"},"mvp-mid-thumb":{"file":"Agrisolare-2-400x240.jpg","width":400,"height":240,"filesize":21861,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-400x240.jpg"},"mvp-small-thumb":{"file":"Agrisolare-2-80x80.jpg","width":80,"height":80,"filesize":2925,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2-80x80.jpg"},"full":{"file":"Agrisolare-2.jpg","width":970,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":284633,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Agrisolare-2.jpg","filename":"Agrisolare-2.jpg","filesize":59826,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/284746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":284633,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/284633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}