{"id":29737,"date":"2022-12-05T12:02:44","date_gmt":"2022-12-05T11:02:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg"},"modified":"2022-12-05T12:02:44","modified_gmt":"2022-12-05T11:02:44","slug":"4a5eeaefc0ae30fe72b28345d6538239","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/12473-il-cosenza-calcio-batte-la-vigor-lamezia-e-torna-in-testa-alla-classifica\/4a5eeaefc0ae30fe72b28345d6538239\/","title":{"rendered":"Pescatore\/Tucci"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-29737","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Pescatore\/Tucci\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg 448w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Pescatore\/Tucci","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":448,"height":299,"file":"2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg","filesize":31491,"sizes":{"medium":{"file":"4a5eeaefc0ae30fe72b28345d6538239-300x200.jpg","width":300,"height":200,"filesize":15626,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239-300x200.jpg"},"thumbnail":{"file":"4a5eeaefc0ae30fe72b28345d6538239-150x150.jpg","width":150,"height":150,"filesize":6470,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239-150x150.jpg"},"full":{"file":"4a5eeaefc0ae30fe72b28345d6538239.jpg","width":448,"height":299,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":29736,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/4a5eeaefc0ae30fe72b28345d6538239.jpg","filename":"4a5eeaefc0ae30fe72b28345d6538239.jpg","filesize":31491,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":29736,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}