{"id":30338,"date":"2022-12-05T12:14:34","date_gmt":"2022-12-05T11:14:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg"},"modified":"2022-12-05T12:14:35","modified_gmt":"2022-12-05T11:14:35","slug":"be6fdae85dd43e9f68cd211aaf3a1de3","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/12801-cosenza-calcio-l-amichevole-con-la-silana\/be6fdae85dd43e9f68cd211aaf3a1de3\/","title":{"rendered":"be6fdae85dd43e9f68cd211aaf3a1de3"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-30338","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg","filesize":35013,"sizes":{"medium":{"file":"be6fdae85dd43e9f68cd211aaf3a1de3-300x227.jpg","width":300,"height":227,"filesize":23865,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3-300x227.jpg"},"thumbnail":{"file":"be6fdae85dd43e9f68cd211aaf3a1de3-150x150.jpg","width":150,"height":150,"filesize":9073,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3-150x150.jpg"},"full":{"file":"be6fdae85dd43e9f68cd211aaf3a1de3.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":30337,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/be6fdae85dd43e9f68cd211aaf3a1de3.jpg","filename":"be6fdae85dd43e9f68cd211aaf3a1de3.jpg","filesize":35013,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":30337,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}