{"id":32237,"date":"2022-12-05T12:54:34","date_gmt":"2022-12-05T11:54:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg"},"modified":"2022-12-05T12:54:34","modified_gmt":"2022-12-05T11:54:34","slug":"3be1082406141b5b7f9933e08d7db29e","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/13792-multato-per-le-condizioni-in-cui-teneva-il-proprio-cane\/3be1082406141b5b7f9933e08d7db29e\/","title":{"rendered":"3be1082406141b5b7f9933e08d7db29e"},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-32237","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg","filesize":21655,"sizes":{"medium":{"file":"3be1082406141b5b7f9933e08d7db29e-300x227.jpg","width":300,"height":227,"filesize":13702,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e-300x227.jpg"},"thumbnail":{"file":"3be1082406141b5b7f9933e08d7db29e-150x150.jpg","width":150,"height":150,"filesize":5668,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e-150x150.jpg"},"full":{"file":"3be1082406141b5b7f9933e08d7db29e.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":32236,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/3be1082406141b5b7f9933e08d7db29e.jpg","filename":"3be1082406141b5b7f9933e08d7db29e.jpg","filesize":21655,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":32236,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}