{"id":33415,"date":"2022-12-05T13:20:48","date_gmt":"2022-12-05T12:20:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg"},"modified":"2022-12-05T13:20:49","modified_gmt":"2022-12-05T12:20:49","slug":"7f3743d224f1a13f9a5ad5c154aa4a79","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/14404-cittadini-boicottano-le-urne-elezioni-non-valide-per-la-seconda-volta-a-roccaforte\/7f3743d224f1a13f9a5ad5c154aa4a79\/","title":{"rendered":"7f3743d224f1a13f9a5ad5c154aa4a79"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-33415","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg","filesize":18633,"sizes":{"medium":{"file":"7f3743d224f1a13f9a5ad5c154aa4a79-300x227.jpg","width":300,"height":227,"filesize":10556,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79-300x227.jpg"},"thumbnail":{"file":"7f3743d224f1a13f9a5ad5c154aa4a79-150x150.jpg","width":150,"height":150,"filesize":4309,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79-150x150.jpg"},"full":{"file":"7f3743d224f1a13f9a5ad5c154aa4a79.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33414,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/7f3743d224f1a13f9a5ad5c154aa4a79.jpg","filename":"7f3743d224f1a13f9a5ad5c154aa4a79.jpg","filesize":18633,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":33414,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}