{"id":33554,"date":"2022-12-05T13:23:43","date_gmt":"2022-12-05T12:23:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg"},"modified":"2022-12-05T13:23:43","modified_gmt":"2022-12-05T12:23:43","slug":"aa53e8bed1d5804f2eb8274d8d582908","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/14476-a-rossano-la-giornata-dell-arte-e-la-notte-di-primavera\/aa53e8bed1d5804f2eb8274d8d582908\/","title":{"rendered":"aa53e8bed1d5804f2eb8274d8d582908"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-33554","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg","filesize":29532,"sizes":{"medium":{"file":"aa53e8bed1d5804f2eb8274d8d582908-300x227.jpg","width":300,"height":227,"filesize":16704,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908-300x227.jpg"},"thumbnail":{"file":"aa53e8bed1d5804f2eb8274d8d582908-150x150.jpg","width":150,"height":150,"filesize":7248,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908-150x150.jpg"},"full":{"file":"aa53e8bed1d5804f2eb8274d8d582908.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33553,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/aa53e8bed1d5804f2eb8274d8d582908.jpg","filename":"aa53e8bed1d5804f2eb8274d8d582908.jpg","filesize":29532,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/33554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":33553,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/33553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}