{"id":37149,"date":"2022-12-05T14:39:32","date_gmt":"2022-12-05T13:39:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82.jpg"},"modified":"2022-12-05T14:39:32","modified_gmt":"2022-12-05T13:39:32","slug":"17102299b595d24504ae8b297b87de82","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/16332-all-unical-il-master-di-1-livello-per-conservatori-di-documenti-digitali\/17102299b595d24504ae8b297b87de82\/","title":{"rendered":"17102299b595d24504ae8b297b87de82"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-37149","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/17102299b595d24504ae8b297b87de82.jpg","filesize":26200,"sizes":{"medium":{"file":"17102299b595d24504ae8b297b87de82-300x227.jpg","width":300,"height":227,"filesize":16084,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82-300x227.jpg"},"thumbnail":{"file":"17102299b595d24504ae8b297b87de82-150x150.jpg","width":150,"height":150,"filesize":6514,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82-150x150.jpg"},"full":{"file":"17102299b595d24504ae8b297b87de82.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":37148,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/17102299b595d24504ae8b297b87de82.jpg","filename":"17102299b595d24504ae8b297b87de82.jpg","filesize":26200,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":37148,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}