{"id":37881,"date":"2022-12-05T14:55:41","date_gmt":"2022-12-05T13:55:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg"},"modified":"2022-12-05T14:55:42","modified_gmt":"2022-12-05T13:55:42","slug":"036ed0e6a3b405e0e41006186ff9376d","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/16711-segrega-in-casa-la-moglie-incinta-e-la-picchia-arrestato-43enne\/036ed0e6a3b405e0e41006186ff9376d\/","title":{"rendered":"036ed0e6a3b405e0e41006186ff9376d"},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-37881","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":450,"height":340,"file":"2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg","filesize":18964,"sizes":{"medium":{"file":"036ed0e6a3b405e0e41006186ff9376d-300x227.jpg","width":300,"height":227,"filesize":12370,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d-300x227.jpg"},"thumbnail":{"file":"036ed0e6a3b405e0e41006186ff9376d-150x150.jpg","width":150,"height":150,"filesize":5332,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d-150x150.jpg"},"full":{"file":"036ed0e6a3b405e0e41006186ff9376d.jpg","width":450,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":37880,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/036ed0e6a3b405e0e41006186ff9376d.jpg","filename":"036ed0e6a3b405e0e41006186ff9376d.jpg","filesize":18964,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":37880,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}