{"id":38506,"date":"2022-12-05T15:09:06","date_gmt":"2022-12-05T14:09:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg"},"modified":"2022-12-05T15:09:08","modified_gmt":"2022-12-05T14:09:08","slug":"b6d5854b45b2d2aba9a292d79d9ceeb2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/17032-sara-tommasi-torna-con-un-calendario-bollente\/b6d5854b45b2d2aba9a292d79d9ceeb2\/","title":{"rendered":"b6d5854b45b2d2aba9a292d79d9ceeb2"},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-38506","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2-200x300.jpg 200w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg 294w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":294,"height":442,"file":"2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg","filesize":17634,"sizes":{"medium":{"file":"b6d5854b45b2d2aba9a292d79d9ceeb2-200x300.jpg","width":200,"height":300,"filesize":10142,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2-200x300.jpg"},"thumbnail":{"file":"b6d5854b45b2d2aba9a292d79d9ceeb2-150x150.jpg","width":150,"height":150,"filesize":3856,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2-150x150.jpg"},"full":{"file":"b6d5854b45b2d2aba9a292d79d9ceeb2.jpg","width":294,"height":442,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":38505,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/b6d5854b45b2d2aba9a292d79d9ceeb2.jpg","filename":"b6d5854b45b2d2aba9a292d79d9ceeb2.jpg","filesize":17634,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38505,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}