{"id":42828,"date":"2022-12-05T17:16:01","date_gmt":"2022-12-05T16:16:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg"},"modified":"2022-12-05T17:16:01","modified_gmt":"2022-12-05T16:16:01","slug":"bed6f683c631de194bbd0fc81158bde5","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/19240-la-svolta-nelle-radici\/bed6f683c631de194bbd0fc81158bde5\/","title":{"rendered":"bed6f683c631de194bbd0fc81158bde5"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-42828","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg","filesize":60611,"sizes":{"medium":{"file":"bed6f683c631de194bbd0fc81158bde5-300x225.jpg","width":300,"height":225,"filesize":18215,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5-300x225.jpg"},"thumbnail":{"file":"bed6f683c631de194bbd0fc81158bde5-150x150.jpg","width":150,"height":150,"filesize":6975,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5-150x150.jpg"},"full":{"file":"bed6f683c631de194bbd0fc81158bde5.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":42827,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/bed6f683c631de194bbd0fc81158bde5.jpg","filename":"bed6f683c631de194bbd0fc81158bde5.jpg","filesize":60611,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":42827,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}