{"id":44733,"date":"2022-12-05T17:55:17","date_gmt":"2022-12-05T16:55:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano.jpg"},"modified":"2022-12-05T17:55:18","modified_gmt":"2022-12-05T16:55:18","slug":"rogliano","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/42697-uomo-ritrovato-cadavere-a-rogliano-allinterno-della-propria-abitazione\/rogliano\/","title":{"rendered":"Rogliano"},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-44733","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":490,"file":"2022\/12\/Rogliano.jpg","filesize":70214,"sizes":{"medium":{"file":"Rogliano-300x200.jpg","width":300,"height":200,"filesize":15060,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano-300x200.jpg"},"thumbnail":{"file":"Rogliano-150x150.jpg","width":150,"height":150,"filesize":6234,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano-150x150.jpg"},"full":{"file":"Rogliano.jpg","width":735,"height":490,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":44732,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Rogliano.jpg","filename":"Rogliano.jpg","filesize":70214,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/44733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":44732,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/44732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}