{"id":46001,"date":"2022-12-05T18:22:22","date_gmt":"2022-12-05T17:22:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111.jpg"},"modified":"2022-12-05T18:22:22","modified_gmt":"2022-12-05T17:22:22","slug":"piazza-santa-teresa-111","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/46498-piazza-santa-teresa-scontro-locali-e-i-residenti-tra-secchiate-dacqua-e-denunce\/piazza-santa-teresa-111\/","title":{"rendered":"piazza-santa-teresa-11"},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-46001","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":491,"file":"2022\/12\/piazza-santa-teresa-111.jpg","filesize":51192,"sizes":{"medium":{"file":"piazza-santa-teresa-111-300x200.jpg","width":300,"height":200,"filesize":12271,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111-300x200.jpg"},"thumbnail":{"file":"piazza-santa-teresa-111-150x150.jpg","width":150,"height":150,"filesize":5163,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111-150x150.jpg"},"full":{"file":"piazza-santa-teresa-111.jpg","width":735,"height":491,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":46000,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/piazza-santa-teresa-111.jpg","filename":"piazza-santa-teresa-111.jpg","filesize":51192,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":46000,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}