{"id":46540,"date":"2022-12-05T19:13:39","date_gmt":"2022-12-05T18:13:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza.jpg"},"modified":"2022-12-05T19:13:39","modified_gmt":"2022-12-05T18:13:39","slug":"settembre-rendese-piazza","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/48261-presentati-i-primi-appuntamenti-del-settembre-rendese-2015-questanno-compie-mezzo-secolo\/settembre-rendese-piazza\/","title":{"rendered":"settembre Rendese piazza"},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-46540","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"118\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza-300x118.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza-300x118.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":288,"file":"2022\/12\/settembre-Rendese-piazza.jpg","filesize":44470,"sizes":{"medium":{"file":"settembre-Rendese-piazza-300x118.jpg","width":300,"height":118,"filesize":10512,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza-300x118.jpg"},"thumbnail":{"file":"settembre-Rendese-piazza-150x150.jpg","width":150,"height":150,"filesize":7131,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza-150x150.jpg"},"full":{"file":"settembre-Rendese-piazza.jpg","width":735,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":46539,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/settembre-Rendese-piazza.jpg","filename":"settembre-Rendese-piazza.jpg","filesize":44470,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":46539,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}