{"id":48110,"date":"2022-12-05T19:47:37","date_gmt":"2022-12-05T18:47:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia.jpg"},"modified":"2022-12-05T19:47:38","modified_gmt":"2022-12-05T18:47:38","slug":"spara-moglie-polizia","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/54284-insegue-in-auto-lex-moglie-e-le-spara-contro-arrestato-63enne\/spara-moglie-polizia\/","title":{"rendered":"polizia"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-48110","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"polizia\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"polizia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":413,"file":"2022\/12\/spara-moglie-polizia.jpg","filesize":46251,"sizes":{"medium":{"file":"spara-moglie-polizia-300x169.jpg","width":300,"height":169,"filesize":12121,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia-300x169.jpg"},"thumbnail":{"file":"spara-moglie-polizia-150x150.jpg","width":150,"height":150,"filesize":5783,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia-150x150.jpg"},"full":{"file":"spara-moglie-polizia.jpg","width":735,"height":413,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":48109,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/spara-moglie-polizia.jpg","filename":"spara-moglie-polizia.jpg","filesize":46251,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":48109,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}