{"id":50339,"date":"2022-12-05T20:35:13","date_gmt":"2022-12-05T19:35:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende.jpg"},"modified":"2022-12-05T20:35:14","modified_gmt":"2022-12-05T19:35:14","slug":"poste-rende","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/64795-rende-tre-malviventi-assaltano-lufficio-postale-centrale-scappati-senza-bottino\/poste-rende\/","title":{"rendered":"poste rende"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-50339","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"149\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende-300x149.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende-300x149.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":364,"file":"2022\/12\/poste-rende.jpg","filesize":40714,"sizes":{"medium":{"file":"poste-rende-300x149.jpg","width":300,"height":149,"filesize":11768,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende-300x149.jpg"},"thumbnail":{"file":"poste-rende-150x150.jpg","width":150,"height":150,"filesize":6094,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende-150x150.jpg"},"full":{"file":"poste-rende.jpg","width":735,"height":364,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":50338,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/poste-rende.jpg","filename":"poste-rende.jpg","filesize":40714,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":50338,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}