{"id":52903,"date":"2022-12-05T22:12:55","date_gmt":"2022-12-05T21:12:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3.jpg"},"modified":"2022-12-05T22:12:55","modified_gmt":"2022-12-05T21:12:55","slug":"polizia-suicidio-4","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/75772-ucciso-un-imprenditore-in-un-agguato\/polizia-suicidio-4\/","title":{"rendered":"polizia-suicidio"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-52903","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3-300x203.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":405,"file":"2022\/12\/polizia-suicidio-3.jpg","filesize":37783,"sizes":{"medium":{"file":"polizia-suicidio-3-300x203.jpg","width":300,"height":203,"filesize":14526,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3-300x203.jpg"},"thumbnail":{"file":"polizia-suicidio-3-150x150.jpg","width":150,"height":150,"filesize":6472,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3-150x150.jpg"},"full":{"file":"polizia-suicidio-3.jpg","width":600,"height":405,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":52902,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/polizia-suicidio-3.jpg","filename":"polizia-suicidio-3.jpg","filesize":37783,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":52902,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}