{"id":53025,"date":"2022-12-05T22:15:26","date_gmt":"2022-12-05T21:15:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri..jpg"},"modified":"2022-12-05T22:15:26","modified_gmt":"2022-12-05T21:15:26","slug":"comune-cosenza-scontri","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/76250-occhiuto-spodestato-non-coop-rom-tagli-garantire-poltrone\/comune-cosenza-scontri\/","title":{"rendered":"comune-cosenza-scontri."},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-53025","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri..jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri.-300x195.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri.-300x195.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri..jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":260,"file":"2022\/12\/comune-cosenza-scontri..jpg","filesize":20093,"sizes":{"medium":{"file":"comune-cosenza-scontri.-300x195.jpg","width":300,"height":195,"filesize":14434,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri.-300x195.jpg"},"thumbnail":{"file":"comune-cosenza-scontri.-150x150.jpg","width":150,"height":150,"filesize":6404,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri.-150x150.jpg"},"full":{"file":"comune-cosenza-scontri..jpg","width":400,"height":260,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri..jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":53024,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/comune-cosenza-scontri..jpg","filename":"comune-cosenza-scontri..jpg","filesize":20093,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":53024,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}