{"id":54077,"date":"2022-12-05T22:36:24","date_gmt":"2022-12-05T21:36:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1.jpg"},"modified":"2022-12-05T22:36:24","modified_gmt":"2022-12-05T21:36:24","slug":"ospedale-vibo-valentia-8227a-2","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/80376-si-dimettono-15-primari-dellospedale-vibo-valentia\/ospedale-vibo-valentia-8227a-2\/","title":{"rendered":"ospedale-vibo-valentia-8227a"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-54077","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"ospedale-vibo-valentia-8227a\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"ospedale-vibo-valentia-8227a","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":360,"file":"2022\/12\/ospedale-vibo-valentia-8227a-1.jpg","filesize":34488,"sizes":{"medium":{"file":"ospedale-vibo-valentia-8227a-1-300x169.jpg","width":300,"height":169,"filesize":12433,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1-300x169.jpg"},"thumbnail":{"file":"ospedale-vibo-valentia-8227a-1-150x150.jpg","width":150,"height":150,"filesize":5941,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1-150x150.jpg"},"full":{"file":"ospedale-vibo-valentia-8227a-1.jpg","width":640,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":54076,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ospedale-vibo-valentia-8227a-1.jpg","filename":"ospedale-vibo-valentia-8227a-1.jpg","filesize":34488,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":54076,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}