{"id":54470,"date":"2022-12-05T22:44:15","date_gmt":"2022-12-05T21:44:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno.jpg"},"modified":"2022-12-05T22:44:15","modified_gmt":"2022-12-05T21:44:15","slug":"progetto-arcobaleno","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/81870-progetto-arcobaleno-divise-sportive-bambini-del-kenya\/progetto-arcobaleno\/","title":{"rendered":"progetto arcobaleno"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-54470","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno-300x214.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":500,"file":"2022\/12\/progetto-arcobaleno.jpg","filesize":57733,"sizes":{"medium":{"file":"progetto-arcobaleno-300x214.jpg","width":300,"height":214,"filesize":16472,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno-300x214.jpg"},"thumbnail":{"file":"progetto-arcobaleno-150x150.jpg","width":150,"height":150,"filesize":7486,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno-150x150.jpg"},"full":{"file":"progetto-arcobaleno.jpg","width":700,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":54469,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/progetto-arcobaleno.jpg","filename":"progetto-arcobaleno.jpg","filesize":57733,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":54469,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}