{"id":5453,"date":"2022-12-04T14:16:49","date_gmt":"2022-12-04T13:16:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg"},"modified":"2022-12-04T14:16:49","modified_gmt":"2022-12-04T13:16:49","slug":"77b4cce0b69b99bdd89ed5fe2f72704d","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/2020-a3-traffico-bloccato-tra-bagnara-e-scilla-direzione-sud\/77b4cce0b69b99bdd89ed5fe2f72704d\/","title":{"rendered":"77b4cce0b69b99bdd89ed5fe2f72704d"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-5453","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg","filesize":59260,"sizes":{"medium":{"file":"77b4cce0b69b99bdd89ed5fe2f72704d-300x225.jpg","width":300,"height":225,"filesize":19530,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d-300x225.jpg"},"thumbnail":{"file":"77b4cce0b69b99bdd89ed5fe2f72704d-150x150.jpg","width":150,"height":150,"filesize":7576,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d-150x150.jpg"},"full":{"file":"77b4cce0b69b99bdd89ed5fe2f72704d.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5452,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/77b4cce0b69b99bdd89ed5fe2f72704d.jpg","filename":"77b4cce0b69b99bdd89ed5fe2f72704d.jpg","filesize":59260,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5452,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}