{"id":54835,"date":"2022-12-05T22:51:49","date_gmt":"2022-12-05T21:51:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis.jpg"},"modified":"2022-12-05T22:51:50","modified_gmt":"2022-12-05T21:51:50","slug":"iper-spar-metropolis","status":"inherit","type":"attachment","link":"https:\/\/quicosenza.it\/news\/83278-anche-liperspar-al-capolinea-morrone-fronte-nazionale\/iper-spar-metropolis\/","title":{"rendered":"Iper spar metropolis"},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-54835","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis-300x227.jpg\" class=\"attachment-medium size-medium\" alt=\"Iper spar metropolis\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis-300x227.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis.jpg 576w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Iper spar metropolis","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":576,"height":435,"file":"2022\/12\/Iper-spar-metropolis.jpg","filesize":41297,"sizes":{"medium":{"file":"Iper-spar-metropolis-300x227.jpg","width":300,"height":227,"filesize":16592,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis-300x227.jpg"},"thumbnail":{"file":"Iper-spar-metropolis-150x150.jpg","width":150,"height":150,"filesize":6657,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis-150x150.jpg"},"full":{"file":"Iper-spar-metropolis.jpg","width":576,"height":435,"mime_type":"image\/jpeg","source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":54834,"source_url":"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Iper-spar-metropolis.jpg","filename":"Iper-spar-metropolis.jpg","filesize":41297,"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":54834,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}