{"id":100243,"date":"2018-10-27T09:20:12","date_gmt":"2018-10-27T07:20:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/serie-b-il-consiglio-di-stato-a-favore-della-lega-si-torna-a-19-squadre\/"},"modified":"2023-01-16T19:01:30","modified_gmt":"2023-01-16T18:01:30","slug":"261366-serie-b-il-consiglio-di-stato-a-favore-della-lega-si-torna-a-19-squadre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/261366-serie-b-il-consiglio-di-stato-a-favore-della-lega-si-torna-a-19-squadre\/","title":{"rendered":"Serie B, il Consiglio di Stato a favore della Lega: &#8220;sospesa la decisione del Tar&#8221;"},"content":{"rendered":"<h4>Il Consiglio di Stato ha sospeso in via cautelare il pronunciamento con cui il Tar del Lazio, tre giorni fa, aveva aveva accolto le istanze del Pro Vercelli e del Novara<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; <strong>Ennesimo ribaltone sul format del torneo<\/strong>: almeno per il momento restano in vigore tutti i provvedimenti della Lega di serie B che il Tar aveva invece &#8216;bloccato&#8217; accogliendo il ricorso dei ricorrenti solo 3 giorni fa. Per ora, dunque, la Serie B resta a 19 squadre. Il Consiglio di Stato ha fissato per il 15 novembre una camera di consiglio per esaminare la questione, accogliendo la richiesta di sospensiva avanzata dalla Lega di Serie B. Intanto, tornano in vigore tutti quei provvedimenti che il Tar aveva sospeso solo pochi giorni fa, a cominciare dal provvedimento <strong>con cui il 13 agosto l\u2019allora commissario Fabbricini blocc\u00f2 i ripescaggi.\u00a0<\/strong>La valutazione del Consiglio di Stato ribalta il giudizio dei colleghi, rilevando che \u201cnon appare sussistere un sufficiente fumus boni iuris in merito all\u2019effettivo superamento \u2013 da parte del Commissario Straordinario della F.I.G.C. nell\u2019adozione degli atti impugnati \u2013 dei limiti della delega conferitagli\u201d.<\/p>\n<p>E in merito agli interessi in campo, per il Consiglio di Stato \u201cnel dovuto bilanciamento tra gli interessi contrapposti, quello generale alla sicurezza e garanzia del regolare ulteriore svolgimento dei campionati ormai gi\u00e0 in corso allo stato permane prevalente, anche per la sua ora accentuata caratterizzazione\u201d. Con la nona giornata in corso di svolgimento, per i giudici amministrativi di secondo grado \u201cappaiono sussistere i presupposti di estrema gravit\u00e0 ed urgenza, tale da non consentire neppure la dilazione fino alla data della camera di consiglio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Consiglio di Stato ha sospeso in via cautelare il pronunciamento con cui il Tar del Lazio, tre giorni fa, aveva aveva accolto le istanze del Pro Vercelli e del Novara<\/p>\n","protected":false},"author":24,"featured_media":100244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-100243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100243"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100244"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}