{"id":100303,"date":"2018-10-29T06:18:00","date_gmt":"2018-10-29T05:18:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/eroina-cocaina-e-hashish-smantellato-un-gruppo-di-pusher-attivi-nel-centro-storico\/"},"modified":"2023-01-16T19:01:33","modified_gmt":"2023-01-16T18:01:33","slug":"261694-eroina-cocaina-e-hashish-smantellato-un-gruppo-di-pusher-attivi-nel-centro-storico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/261694-eroina-cocaina-e-hashish-smantellato-un-gruppo-di-pusher-attivi-nel-centro-storico\/","title":{"rendered":"Eroina, cocaina e hashish, smantellato un gruppo di pusher attivi nel centro storico (VIDEO e NOMI)"},"content":{"rendered":"<h4>Operazione all&#8217;alba della Squadra Mobile della Questura di Cosenza contro un gruppo di spacciatori attivi in citt\u00e0. <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Ancora un blitz contro lo spaccio di droga a Cosenza. Alle prime ore di oggi la Squadra Mobile ha dato esecuzione ad un ordinanza di applicazione di misure cautelari, emesse dal Gip del tribunale di Cosenza, nei confronti <strong>13 persone<\/strong>. I provvedimenti richiesti dalla Procura bruzia, riguardano soggetti ritenuti responsabili di detenzione, cessione di<strong> cocaina, hashish ed eroina,<\/strong> nonch\u00e8 di estorsione.<\/p>\n<p>Le indagini condotte dal persone della Polizia di Cosenza hanno consentito di disarticolare un gruppo di pusher operante in particolar modo <strong>nel centro storico della citt\u00e0<\/strong> e nel corso delle indagini sono stati effettuati numerosi riscontri e sequestri di stupefacenti.<\/p>\n<h4>La morte di una donna per overdose nel 2016<\/h4>\n<p>Il blitz \u00e8 legato alle indagini sulla morte di una donna, deceduta per overdose nel dicembre 2016 <strong>in via Rivocati<\/strong>. Il successivo rinvenimento di sostanza stupefacente dello stesso tipo di quella che aveva causato la sua morte, durante una perquisizione effettuata nei confronti di un soggetto noto per precedenti specifici, aveva determinato nell&#8217;immediato un&#8217;attivit\u00e0 di indagine nei suoi confronti. Indagine che ha poi portato alla scoperta dell&#8217;organizzazione.<\/p>\n<h2>I dettagli dell&#8217;operazione<\/h2>\n<p>Per due persone \u00e8 stata disposta l&#8217;applicazione della custodia cautelare in carcere mentre per un soggetto \u00e8 stato applicato il regime dei domiciliari con il braccialetto elettronico. Ancora, per altre sei persone, disposti gli arresti domiciliari presso l&#8217;abitazione di residenza e per altri 4 soggetti, misura di divieto di dimora nel Comune di Cosenza. Una donna risulta indagata in stato di libert\u00e0.<\/p>\n<p>Tra i particolari delle indagini emerge come, <strong>nell&#8217;agosto 2016,<\/strong> a seguito di una perquisizione nel quartiere popolare di via Popilia, nell&#8217;abitazione di un soggetto con precedenti specifici in materia di stupefacenti, era stata trovata una certa quantit\u00e0 di eroina e materiale per il confezionamento, nonch\u00e8 denaro contante. Poi la morte a <strong>dicembre<\/strong> della donna per overdose, e la seconda indagine avviata a seguito del decesso in <strong>via Rivocati<\/strong>. La donna sarebbe morta utilizzando la stessa droga trovata durante una perquisizione di un soggetto sul quale, ovviamente si sono concentrate le indagini degli inquirenti. <strong>Le due attivit\u00e0 sono state per\u00f2 riunite<\/strong> perch\u00e8 avevano diversi punti in comune e grazie ad intercettazioni telefoniche, ambientali, perquisizioni e sequestri, \u00e8 stato possibile fare piena luce sull&#8217;esistenza di un gruppo di persone, che di fatto,<strong>\u00a0 spacciavano a Cosenza e nell&#8217;hinterland.<\/strong><\/p>\n<p>E&#8217; stato possibile infatti, accertare numerosi episodi di spaccio attraverso appostamenti e pedinamenti con relativo sequestro anche di singole dosi. Acquisite in quelle occasioni le dichiarazioni degli acquirenti della droga, \u00e8 stato possibile arrivare al quadro probatorio che ha portato oggi alle ordinanze emesse contro i 13 indagati.<\/p>\n<h3>Lo spaccio &#8220;lampo&#8221; delle dosi<\/h3>\n<p>L&#8217;attivit\u00e0 dei pusher avveniva con una certa velocit\u00e0 e lo spaccio avveniva maggiormente presso le abitazioni degli stessi spacciatori o nelle vie limitrofe. Incontri lampo fissati al telefono<strong>. E ci si metteva d&#8217;accordo utilizzando un linguaggio in codice<\/strong>. Inoltre gli indagati, spesso cambiavano le modalit\u00e0 o le schede telefoniche per tentare di evitare di essere rintracciati. A rendere complessa l&#8217;attivit\u00e0 di indagine soprattutto i luoghi dove era difficile, per gli inquirenti, accedere ad esempio, con auto di servizio.<\/p>\n<p>&nbsp;<\/p>\n<h3>DESTINATARI DI MISURE CAUTELARI<\/h3>\n<p>&nbsp;<\/p>\n<p>F. V., di Cosenza di anni 44 \u2013 divieto di dimora<\/p>\n<p>Stefano Salerno di anni 33 \u2013 detenzione carceraria<\/p>\n<p>Domenico Salerno di anni 54 \u2013 arresti domiciliari<\/p>\n<p>Alessandro Furfaro di anni 30 \u2013 arresti domiciliari<\/p>\n<p>Fausto Vezzoni di anni 38 \u2013 arresti domiciliari<\/p>\n<p>F. M., di Cosenza di anni 38 \u2013 divieto di dimora<\/p>\n<p>Antonio Belsito di anni 54 \u2013 arresti domiciliari<\/p>\n<p>Amedeo Mazzocca di anni 39 \u2013 detenzione carceraria<\/p>\n<p>M. P. C.\u00a0 di anni 36 \u2013 divieto di dimora<\/p>\n<p>Alessandro Morrone di anni 30 \u2013 arresti domiciliari<\/p>\n<p>Mario Ariello di anni 41 \u2013 arresti domiciliari<\/p>\n<p>O. B.\u00a0 di anni 28 \u2013 divieto di dimora<\/p>\n<p>Francesco Mazzei di anni 24 \u2013 arresti domiciliari<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Cosenza Vecchia, arresti per spaccio di stupefacenti edestorsioni\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/B-d02O7Y-24?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operazione all&#8217;alba della Squadra Mobile della Questura di Cosenza contro un gruppo di spacciatori attivi in citt\u00e0.<\/p>\n","protected":false},"author":22,"featured_media":100304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-100303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100303"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100304"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}