{"id":100461,"date":"2018-11-01T15:55:13","date_gmt":"2018-11-01T14:55:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/container-di-via-degli-stadi-appello-ai-senzatetto-non-restate-in-strada-venite-qua\/"},"modified":"2023-01-16T19:01:44","modified_gmt":"2023-01-16T18:01:44","slug":"262270-container-di-via-degli-stadi-appello-ai-senzatetto-non-restate-in-strada-venite-qua","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/262270-container-di-via-degli-stadi-appello-ai-senzatetto-non-restate-in-strada-venite-qua\/","title":{"rendered":"Container di via degli Stadi, appello ai senzatetto: &#8220;Non restate in strada, venite qua&#8221;"},"content":{"rendered":"<h4>Le strutture allestite per ospitare persone in difficolt\u00e0 sono aperte a tutti i clochard<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;Anche per questo inverno &#8211; garantisce Franco Corbelli del Movimento Diritti Civili &#8211; resteranno aperti e operativi e pronti ad accogliere, tutti i giorni, clochard, uomini, donne e bambini, di Cosenza e dei centri vicini i due container della Protezione Civile calabrese che due anni fa, il 28 ottobre 2016, su iniziativa del leader del Movimento Diritti Civili ed (ex) delegato della Presidenza della Regione per la tutela e la promozione dei diritti umani, Franco Corbelli, <strong>sono stati (in una giornata, come oggi, di pioggia) portati a Cosenza e installati, in via degli Stadi, nell\u2019area ex Afor, oggi Calabria Verde.<\/strong> Un \u201cpiccolo, grande miracolo\u201d reso possibile grazie al sostegno della Regione Calabria, del Presidente Mario Oliverio, del suo Capo di Gabinetto, Gaetano Pignanelli, e del Dirigente regionale della Protezione Civile, Carlo Tansi, che hanno subito sostenuto l\u2019iniziativa di Corbelli.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Il sogno di Padre Fedele, dei suoi due storici collaboratori, Teresa Boero e Giovanni Valentino, e di Diritti Civili, di dare un tetto dignitoso (anche se provvisorio), ai poveri e senzatetto, continua. E a loro oggi, a quelli che vivono ancora in strada, Corbelli rivolge un accorato appello, invitandoli, <strong>\u201cadesso che \u00e8 arrivato l\u2019inverno, con le prime piogge e il freddo, a lasciare la strada e ad accettare l\u2019ospitalit\u00e0<\/strong> nei due container, luogo di accoglienza, di reale inclusione, dove migranti del mondo, extracomunitari, nostri concittadini e connazionali convivono dignitosamente aiutandosi reciprocamente. Quei due container sono la vera casa di accoglienza del Signore sempre aperta a tutti i poveri del mondo\u201d. Al frate missionario e ai suoi due storici collaboratori, Teresa Boero e Giovanni Valentino, il leader di Diritti Civili ha voluto subito, due anni fa, affidare la completa gestione dei due container.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>I primi mesi a sorvegliare la notte le due strutture, ad assistere i clochard che avevano bisogno, era stato messo anche un custode che aveva pagato Corbelli con la sua indennit\u00e0 regionale, cos\u00ec come quando si sono dovuti effettuare alcuni lavori di riparazione che Corbelli e Padre Fedele hanno personalmente sostenuto economicamente. <strong>I due container, in questi due anni, sono sempre, ogni giorno, rimasti aperti e operativi,<\/strong> anche durante l\u2019estate con all\u2019interno un servizio di aria condizionata. Cos\u00ec come adesso per l\u2019inverno avranno di nuovo (gratuitamente, grazie alla Regione) i riscaldamenti, due televisori e bagni annessi. Anche il Commissario di Calabria Verde, il generale Aloisio Mariggi\u00f2, quando \u00e8 stato necessario, investito da Corbelli, \u00e8 subito intervenuto per la risoluzione di alcuni piccoli problemi createsi nei due container.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIn oltre 30 anni ho fatto mille importanti battaglie civili e grandi iniziative umanitarie, nazionali e internazionali, <strong>questa dei container \u00e8 sicuramente una delle conquiste pi\u00f9 belle, a cui sono e rester\u00f2 sempre particolarmente affezionato<\/strong>. Dare un tetto ai clochard. Una promessa che avevo fatto a Padre Fedele e ai suoi due angeli custodi , Teresa e Giovanni, che, come gli ho ribadito ancora una volta anche oggi per telefono, sono contento di aver potuto mantenere, afferma Corbelli. Una iniziativa di solidariet\u00e0, accoglienza e di grande civilt\u00e0 che ha scongiurato in questi due anni che a Cosenza si verificasse qualche tragedia, con la morte per il freddo e il gelo di qualche clochard, come \u00e8 purtroppo invece avvenuto in tante importanti e civili grandi citt\u00e0 italiane, dal Nord al Sud.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A Cosenza (unica citt\u00e0 d\u2019Italia ad aver utilizzato dei container per ospitare i senzatetto) questi drammi sono stati, grazie a Dio, evitati.<strong> I clochard sono stati tolti dalla strada, da sotto i ponti, dalla panchine dove vivevano in condizioni disumane e allucinanti.<\/strong> Tante le storie di grande umanit\u00e0 (alcune purtroppo anche triste, di chi si \u00e8 spento serenamente in quella umile e dignitosa casa di Dio) che si sono vissute in quei due container, in questi due anni. Solo chi si \u00e8 rifiutato e non ha voluto (soltanto pochi, per fortuna) non ha trovato riparo nei due container. Per il resto in quei due container c\u2019\u00e8 stato e ci sar\u00e0 sempre posto per i poveri e i senzatetto\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">LEGGI ANCHE<\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/4132\" target=\"_blank\" rel=\"noopener\">\u00a0<span class=\"current\">A Cosenza container per i senzatetto davanti al palazzo vuoto di Calabria Verde (FOTO)<\/span><\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le strutture allestite per ospitare persone in difficolt\u00e0 sono aperte a tutti i clochard<\/p>\n","protected":false},"author":22,"featured_media":100462,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-100461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100461"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100462"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}