{"id":100611,"date":"2018-11-06T06:00:01","date_gmt":"2018-11-06T05:00:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-s-donato-di-ninea-e-stato-inaugurato-lostello-della-gioventu\/"},"modified":"2023-01-16T19:01:54","modified_gmt":"2023-01-16T18:01:54","slug":"262829-a-s-donato-di-ninea-e-stato-inaugurato-lostello-della-gioventu","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/262829-a-s-donato-di-ninea-e-stato-inaugurato-lostello-della-gioventu\/","title":{"rendered":"A S. Donato di Ninea \u00e8 stato inaugurato l\u2019ostello della giovent\u00f9"},"content":{"rendered":"<h4><span class=\"primamaiuscola\">U<\/span>na struttura antica recuperata, perfettamente inserita nel particolare contesto del cuore storico di un borgo che difende la sua identit\u00e0 e ne fa valore.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; E&#8217; stato il presidente della Regione Mario Oliverio, alla presenza del sindaco Jim Di Giorno, a tagliare il nastro. Durante la\u00a0ventottesima\u00a0<strong>\u201cFesta d\u2019Autunno\u201d<\/strong> che ha riempito nel paese, come negli anni passati, vicoli e viuzze con centinaia di presenze. Nell\u2019Ostello, <strong>22 posti letto,<\/strong> ristrutturato con il sostegno della Regione (fondi Por 2007-2013), in occasione dell\u2019avvio ufficiale delle attivit\u00e0, un convegno tenuto subito dopo il taglio del nastro ha unito pi\u00f9\u00a0 interventi anche intorno all\u2019enogastronomia di qualit\u00e0, componente rilevante del territorio cui la Regione destina particolare attenzione, riconosciuta e analizzata quale forte attrattore sotto il profilo turistico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-262834 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/3676735b-4a14-4269-b563-9c29f60d58f41-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" title=\"\"><\/p>\n<p>A partecipare al convegno che ha seguito l\u2019inaugurazione dell\u2019Ostello della Giovent\u00f9, coordinato da Adriana Amodio,\u00a0 sono stati l\u2019assessore comunale ai Lavori Pubblici <strong>Angelo De Maio<\/strong>; i consiglieri regionali <strong>Franco Sergio<\/strong> e <strong>Giuseppe Aieta<\/strong>; il presidente del Parco del Pollino <strong>Domenico Pappaterra<\/strong>; il consigliere della Provincia di Cosenza <strong>Graziano Di Natale<\/strong>; lo chef ed imprenditore <strong>Enzo Barbieri<\/strong>;\u00a0 i sindaci San Sosti <strong>Vincenzo De Marco<\/strong> e di Fiorano Modenese, <strong>Francesco Tosi<\/strong>; <strong>Luigi Tinozzi<\/strong>, in rappresentanza della citt\u00e0 di Venaria;<strong> Tommaso Ferraro<\/strong> della comunit\u00e0 sandonatese che vive in Francia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una struttura antica recuperata, perfettamente inserita nel particolare contesto del cuore storico di un borgo che difende la sua identit\u00e0 e ne fa valore.<\/p>\n","protected":false},"author":20,"featured_media":100612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41],"tags":[],"class_list":["post-100611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100611"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100612"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}