{"id":100655,"date":"2018-11-06T13:00:23","date_gmt":"2018-11-06T12:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/consegnati-i-premi-per-lottava-edizione-di-verde-ambiente-2018\/"},"modified":"2023-01-16T19:01:57","modified_gmt":"2023-01-16T18:01:57","slug":"263006-consegnati-i-premi-per-lottava-edizione-di-verde-ambiente-2018","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/263006-consegnati-i-premi-per-lottava-edizione-di-verde-ambiente-2018\/","title":{"rendered":"Consegnati i premi per l&#8217;ottava edizione di &#8220;Verde Ambiente 2018&#8221;"},"content":{"rendered":"<h4>A Sorrento, domenica scorsa, si \u00e8 tenuta l\u2019assegnazione l\u2019ottava edizione del Premio \u201cVerde Ambiente 2018\u201d. Tra i premiati anche il sindaco di Riace Mimmo Lucano che per\u00f2 era assente.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SORRENTO &#8211; La Sala Consiliare del Comune di Sorrento ha ospitato la cerimonia promossa dall\u2019associazione ambientalista VAS (Verdi Ambiente e Societ\u00e0), di premiazione dell\u2019ottava edizione del &#8220;Premio Internazionale di Ecologia Verde Ambiente 2018&#8221;. <strong>Il premio, creato nel 2010 dai VAS assieme al periodico di politica, scienza e tecnica \u201cVerde Ambiente\u201d,<\/strong> ha la finalit\u00e0 di <strong>individuare personalit\u00e0 italiane ed internazionali impegnate a difesa dell\u2019ambiente, dei diritti civili e sociali<\/strong> e di tutti coloro che si trovano a lottare quotidianamente per proteggere un ambiente e un territorio che si mostra ogni giorno pi\u00f9 fragile, come dimostrano le distruzioni ambientali di questi ultimi mesi.<\/p>\n<p>Effetti distruttivi dovuti non solo alla furia degli elementi meteorologici ma, in gran parte, all\u2019incuria di chi dovrebbe tutelare le importanti risorse ambientali. Siamo sicuramente al centro di cambiamenti epocali, perdite di importanti biodiversit\u00e0, ostaggi e vittime indifese di eventi estremi, mentre continua a mancare una razionale politica ambientale che privilegi e incentivi l\u2019uso delle energie rinnovabili, il riciclo dei materiali di uso quotidiano e limiti consumi e sprechi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-263035  aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/Premio-VAS-02.jpg\" alt=\"\" width=\"602\" height=\"355\" title=\"\"><\/p>\n<p>A margine della cerimonia di premiazione quest\u2019anno si \u00e8 svolta, presso Villa Fiorentino a Sorrento, nel pomeriggio di sabato 3 novembre un\u2019interessante e affollata assemblea pubblica dal tema:\u201dCriminalit\u00e0, sicurezza e controllo democratico del territorio\u201d, condotta dal giornalista Riccardo Iacona e che ha visto, tra gli altri, gli interventi del Procuratore Nazionale Antimafia, <strong>Federico Cafiero De Raho,<\/strong> della senatrice Loredana De Petris, di Daniele Granara, vicepresidente di VAS e dell&#8217;ex Presidente della II Sez. penale della suprema Corte di Cassazione Antonio Esposito.<\/p>\n<p>Lo stesso Esposito \u00e8 intervenuto all&#8217;inizio della cerimonia di premiazione e ha ricordato come opporsi all\u2019illegalit\u00e0 della gestione dell\u2019ambiente parte anche dal contrasto agli effetti dei innumerevoli condoni edilizi introdotti negli ultimi 20 anni che tanti danni hanno prodotto e stanno producendo proprio in questi giorni su tutti il territorio del nostro paese.<\/p>\n<p>\u00c8 seguito l\u2019intervento introduttivo del <strong>Presidente di VAS, Guido Pollice,<\/strong> che ha messo in evidenza che il titolo di questa ottava edizione del premio (\u201cL\u2019eta dell\u2019antropocene\u201d) vuole ricordare come la presenza dell&#8217;uomo sul pianeta lascer\u00e0 tracce, rilevabili anche fra decine o centinaia di migliaia di anni, dei profondi cambiamenti ambientali, soprattutto in senso negativo, dovuti all&#8217;attivit\u00e0 inquinante e di sfruttamento intensivo delle risorse da parte degli esseri umani.<\/p>\n<p>I premiati di questa nuova edizione sono stati: Francesco Cuomo, saggista e blogger ambientalista campano, Claudio D&#8217;Esposito, attivista del WWF nella territorio sorrentino, Loredana De Petris , senatrice e nota ambientalista, Don Virginio Colmegna, della Fondazione Casa della carit\u00e0 di Milano, da anni in prima fila per l\u2019aiuto alle persone bisognose e in difficolt\u00e0 e <strong>Riccardo Iacona<\/strong>, rinomato giornalista di origini calabresi, noto per le sue inchieste e denuncie di grande impatto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-263034  aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/Iacona-Premio-VAS-01.jpg\" alt=\"\" width=\"574\" height=\"328\" title=\"\"><\/p>\n<p>Sono stati premianti, inoltre, Enrico Loccioni, innovativo imprenditore marchigiano ideatore di un modello per misurare e migliorare la qualit\u00e0 di prodotti e processi dell\u2019industria, Massimo Piras, ideatore della campagna \u201cCambiamo l\u2019Aria\u201d del movimento &#8220;Rifiuti zero&#8221;, Giovan Battista Polentes, imprenditore che ha saputo coniugare la sapienza artigianale con l\u2019innovazione tecnologica, e, infine, Tawfik El Sayed, giovane migrante egiziano, che dopo aver attraversato il Mediterraneo ed essere accolto a Milano dalla Fondazione \u201cCasa della carit\u00e0\u201d, ha saputo conquistare la sua autonomia lavora e studiando Economia all\u2019universit\u00e0<\/p>\n<p>Tra i premiati, <strong>assenti giustificati<\/strong> alla manifestazione, ricordiamo Marica Branchesi, nota astrofisica, Antonino Di Matteo, Procuratore nazionale antimafia, <strong>Mimmo Lucano,<\/strong> sindaco (sospeso) di Riace al centro del controverso caso della gestione dei rifugiati politici e immigrati in genere e ideatore di un modello di integrazione nella comunit\u00e0 locale, famoso in tutto il mondo e, infine Andrea Purgatori , giornalista investigativo e Presidente di Greenpeace Italia.<\/p>\n<p>Sono state assegnate, nel corso della stessa cerimonia, alcune menzioni speciali a soci di VAS che, come si legge nella presentazione della Giuria, in questi anni hanno scritto, in giro per l\u2019Italia, alcune pagine importanti di storia dell\u2019Associazione. Tra questi Giuseppe Boccia dei VAS Rende &#8211; Cosenza, che ha ricordato come &#8220;una tale menzione \u00e8 certamente da estendere a tutti quei soci che in questi anni hanno portato avanti i valori fondativi dell\u2019Associazione quali (ecopacifismo, biodiversit\u00e0, beni comuni) e permesso lo sviluppo di progetti e iniziative di solidariet\u00e0 sociale, di tutela e valorizzazione della natura e dei beni storico-culturali. Tra i vari progetti, afferma Boccia, vanno ricordati quelli relativi allo sviluppo delle energie rinnovabili, alla salvaguardare il patrimonio boschivo italiano (\u201cPreveniamo gli incendi\u201d), al sostegno dell\u2019agricoltura ecologica e della sicurezza alimentare (Campagna Mangiasano), alla protezione ambientale e all\u2019uso responsabile delle acque e delle coste (Diritti del mare)&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-263033  aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/Boccia-Premio-VAS-04.jpg\" alt=\"\" width=\"557\" height=\"428\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sorrento, domenica scorsa, si \u00e8 tenuta l\u2019assegnazione l\u2019ottava edizione del Premio \u201cVerde Ambiente 2018\u201d. Tra i premiati anche il sindaco di Riace Mimmo Lucano che per\u00f2 era assente.<\/p>\n","protected":false},"author":27,"featured_media":100656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-100655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100655"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100656"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}