{"id":100681,"date":"2018-11-07T09:44:44","date_gmt":"2018-11-07T08:44:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rifiuti-in-mare-poche-ore-prima-del-sequestro-indagini-in-corso-video\/"},"modified":"2023-01-16T19:01:59","modified_gmt":"2023-01-16T18:01:59","slug":"263106-rifiuti-in-mare-poche-ore-prima-del-sequestro-indagini-in-corso-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/263106-rifiuti-in-mare-poche-ore-prima-del-sequestro-indagini-in-corso-video\/","title":{"rendered":"Rifiuti in mare poche ore prima del sequestro, indagini in corso (VIDEO)"},"content":{"rendered":"<h4>Finanziati dalla Regione Calabria 120mila euro, non si trovano 11mila euro per dragare la sabbia che ostruisce il canale degli Stombi. Gettato in mare il materiale di risulta<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASSANO ALLO IONIO (CS) &#8211; Rifiuti in mare a Cassano allo Ionio, nell&#8217;indifferenza dell&#8217;amministrazione comunale. &#8220;L&#8217;associazione Vela S\u00ec &#8211; scrive in una nota il suo presidente Vittorio Cosentino &#8211; chiede alla commissione straordinaria che amministra il Comune di Cassano allo Ionio le motivazioni dello stallo istituzionale che ha determinato il sequestro probatorio della foce del canale degli Stombi da parte della Procura della Repubblica a fronte degli innumerevoli solleciti e soluzioni proposte nel corso degli ultimi 9 mesi dalla stessa associazione. Il 21 febbraio 2018 \u00e8 stato ribadito durante il corso di un incontro con la commissione straordinaria l&#8217;urgenza dell&#8217;adozione da parte del Comune di Cassano allo Ionio di quanto necessario per il completamento dell&#8217;<strong>acquisto di una draga attraverso lo sfruttamento di un fondo di 120mila euro messo a disposizione dalla Regione Calabria.<\/strong> E&#8217; stato successivamente sollecitato il completamento della macchina operatrice.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un acquisto che avrebbe garantito la navigabilit\u00e0 del Canale degli Stombi in maniera definitiva e permanente. <\/strong>Vela S\u00ec nell&#8217;aprile del 2018 ha messo al corrente i commissari del fatto che il consorzio di Bonifica (operante in regime di convenzione con il Comune di Cassano) ha ripreso a prelevare con un proprio escavatore la sabbia accumulatasi all&#8217;interno della foce del canale degli Stombi per poi depositarla all&#8217;esterno del canale e lungo il molo nord. Questa attivit\u00e0 ripetuta con le medesime modalit\u00e0 da anni si \u00e8 rivelata del tutto inutile. L&#8217;associazione ha quindi richiesto in via d&#8217;urgenza di adottare i pi\u00f9 opportuni provvedimenti idonei a rendere pi\u00f9 razionale ed efficace l&#8217;impiego di fondi pubblici al fine di garantire la percorribilit\u00e0 delle imbarcazioni lungo il canale degli Stombi in sicurezza e con rispetto delle prescrizioni dettate dalla Capitaneria di Porto di Corigliano. Tutto ci\u00f2 non ha avuto alcun riscontro da parte della triade commissariale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Diffidati il Comune di Cassano e il Consorzio di Bonifica l&#8217;unica risposta pervenuta \u00e8 stata che i lavori erano temporaneamente sospesi in attesa di conferire a discarica autorizzata il materiale dragata. A luglio al fine di risolvere lo stallo conseguente alla giacenza dei fanghi di dragaggio sulla foce dello Stombi ha fatto effettuare un sopralluogo ai tecnici di una societ\u00e0 autorizzata dalla Regione Calabria al trattamento di tale rifiuto. Trasmesso all&#8217;ufficio tecnico del Comune di Cassano allo Ionio un progetto di manutenzione urgente del canale degli Stombi che avrebbe permesso di livellare la foce del canale senza produzione di fanghi di dragaggio all&#8217;esterno \u00e8 stato trasmesso anche un ulteriore preventivo per lo smaltimento dei fanghi al RUP del Comune con un costo di soli 14,70 euro per ogni tonnellata da smaltire. Nonostante il prezzo sia esiguo i commissari straordinari il 30 agosto hanno comunicato che<strong> i fondi stanziati dalla Regione Calabria per la navigabilit\u00e0 dello Stombi erano insufficienti per qualsiasi intervento. Gli abitanti dei Laghi di Sibari hanno per\u00f2 notato come solo le diverse centinaia di migliaia di euro versate nelle casse comunali sotto forma di IMU avrebbero potuto, con una variazione di bilancio, coprire i costi per scongiurare un disastro ambientale, economico e turistico a carico della sibaritide.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A settembre del 2018 constatato che negli ultimi anni non si era mai ricorsi ad un progetto organico programmatico di dragaggio Vela S\u00ec ha lanciato una progettazione definitiva ed esecutiva degli interventi di mantenimento dell&#8217;efficienza idraulica della foce del canale degli Stombi.<strong> L&#8217;offerta comprendeva anche l&#8217;ottenimento delle relative autorizzazione ed aveva un costo totale di soli 11mila euro.\u00a0<\/strong>Ancora attendiamo una risposta. Chiediamo ai commissari straordinari per quale motivo si sia ancora in una fase di stallo e perch\u00e9 si sia permesso che parte del rifiuto apeciale stoccato sulla foce dello Stombi finisse in mare, tanto a seguito delle intercorse mareggiate, quanto per l&#8217;azione volontaria dei mezzi operanti sul cantiere durante le operazioni ordinate con il provvedimento d&#8217;urgenza del 1 Ottobre. Lo scempio ambientale perpetrato in mare il 6 ottobre poche ore prima che avvenisse il sequestro da parte della Capitaneria di Porto e dei Carabinieri Forestali per sospetta violazione della legge 152\/2006 del Testo unico Ambientale&#8221;. Sul caso ad oggi vi sono indagini in corso.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Canale degli Stombi\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/bW6EOO76TA4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finanziati dalla Regione Calabria 120mila euro, non si trovano 11mila euro per dragare la sabbia che ostruisce il canale degli Stombi. Gettato in mare il materiale di risulta<\/p>\n","protected":false},"author":22,"featured_media":100682,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-100681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100681"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100682"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}