{"id":100735,"date":"2018-11-08T13:18:02","date_gmt":"2018-11-08T12:18:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lontra-ritrovata-tra-le-strade-del-tirreno-cosentino\/"},"modified":"2023-01-16T19:02:02","modified_gmt":"2023-01-16T18:02:02","slug":"263357-lontra-ritrovata-tra-le-strade-del-tirreno-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/263357-lontra-ritrovata-tra-le-strade-del-tirreno-cosentino\/","title":{"rendered":"Lontra ritrovata tra le strade del Tirreno cosentino"},"content":{"rendered":"<h4>Il cucciolo \u00e8 stato recuperato mentre camminava in una via cittadina<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Un cucciolo di lontra (Lutra-Lutra) \u00e8 stato ritrovato ieri da un cittadino lungo una strada nel Comune di Scalea. Il piccolo animale \u00e8 stato subito recuperato dai militari della Stazione Carabinieri Forestale del luogo che lo hanno preso in cura prima di affidarlo al medico veterinario del Parco Nazionale del Pollino che ne ha<strong> constatato le buone condizioni fisiche.<\/strong> Il cucciolo, non essendo autosufficiente, \u00e8 stato trasferito presso il centro di Recupero animali di Policoro in provincia di Matera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-263358 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/lontra-scalea-151x280.jpg\" alt=\"\" width=\"248\" height=\"460\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cucciolo \u00e8 stato recuperato mentre camminava in una via cittadina<\/p>\n","protected":false},"author":22,"featured_media":100736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-100735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100735"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100736"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}