{"id":100768,"date":"2018-11-09T11:48:48","date_gmt":"2018-11-09T10:48:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/moda-autunno-inverno-2019-ecco-i-top-fashion-trends\/"},"modified":"2023-01-16T19:02:05","modified_gmt":"2023-01-16T18:02:05","slug":"263469-moda-autunno-inverno-2019-ecco-i-top-fashion-trends","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/263469-moda-autunno-inverno-2019-ecco-i-top-fashion-trends\/","title":{"rendered":"Moda Autunno &#8211; Inverno 2019, ecco i Top Fashion Trends"},"content":{"rendered":"<h4>Domina il colore argento, forte richiamo agli anni Ottanta, mentre tornano a farsi spazio le stampe animalier e a quadri<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>La collezione Autunno-Inverno 2018-2019 si tinge d&#8217;argento, il colore luminoso delle stelle che \u00e8 diventato il nuovo nero. I brand pi\u00f9 di tendenza del momento hanno utilizzato la passerella come trampolino di lancio verso spazi astrali lontani anni luce, che la donna vestita d&#8217;argento pu\u00f2 sognare di esplorare.<strong> Le tonalit\u00e0 argentate costituiscono un richiamo all&#8217;outfit chic degli anni Ottanta,<\/strong> ritornati prepotentemente alla ribalta con la loro tipica atmosfera fatta di mille luci psichedeliche e di serate glamour con sottofondo di musica disco. Nessun designer ha saputo resistere alla <span style=\"color: #0000ff;\"><em><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5692\" target=\"_blank\" rel=\"noopener\">luminosit\u00e0 glaciale dell&#8217;argento<\/a><\/strong><\/em><\/span>, che viene utilizzato per impreziosire i capi denim della nuova collezione di Christian Dior o per valorizzare con sfumature iridescenti le giacche dalle spalle ampie di Balman.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;attenzione delle case di moda per le questioni riguardanti il rispetto dell&#8217;ambiente e la protezione degli animali ha decretato il rilancio dei capi e degli accessori a stampa animalier, che richiamano la moda dal gusto primitivo lanciata da Dior negli anni &#8217;40. <strong>La tendenza animalier domina con diversi colori le passerelle di tutto il mondo<\/strong> ma questo motivo, apprezzato soprattutto dalla donna che vuole essere sexy, non \u00e8 proprio semplice da indossare in quanto necessita di un <em><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5693\" target=\"_blank\" rel=\"noopener\">abbinamento adeguato<\/a><\/span><\/strong><\/em> capace di esaltarlo. Per la stagione Autunno-Inverno 2019 Max Mara propone un abbinamento quasi tono su tono mettendo sotto ad un maxi cappotto maculato un tubino con gonna anch&#8217;essa a stampa maculata ma con diverse sfumature di colore.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La stampa checked, a quadretti, \u00e8 l&#8217;altro must have della stagione che sar\u00e0 presente sul lungo e sul corto con diverse tipologie di tessuti. Tra i tessuti pi\u00f9 conosciuti c&#8217;\u00e8 l&#8217;intramontabile scozzese tweed in lana robusta che presenta una trama a quadri grandi o piccoli. Utilizzato inizialmente solo per le collezioni maschili, il tweed \u00e8 diventato protagonista della moda femminile grazie al genio creativo di Coco Chanel. Altra<em><strong><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5694\">icona del checked<\/a> <\/span><\/strong><\/em>\u00e8 il motivo pied de poule, che forma effetti bicolore grazie all&#8217;uso di fibre con colori in contrasto come il bianco e il nero. Ad ultimare la lista dedicata alla moda checked non potevano mancare tartan e <strong>principe di Galles, quest&#8217;ultimo deve il suo nome a re Edoardo VIII che soleva portare abiti realizzati con questo particolare tessuto nato dall&#8217;incrocio di quadri grandi e piccoli<\/strong>. Sul sito dell&#8217;aggregatore di moda<em><strong><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5695\">lyst<\/a><\/span><\/strong><\/em> la stagione A\/W 2019 \u00e8 un trionfo di loghi e pieghe, che sono tornate sulle gonne di diverse lunghezze per donare all&#8217;outfit femminile quel particolare tocco di leggerezza assente ormai da troppe stagioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domina il colore argento, forte richiamo agli anni Ottanta, mentre tornano a farsi spazio le stampe animalier e a quadri<\/p>\n","protected":false},"author":22,"featured_media":100769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42,22,572,92,28,7],"tags":[],"class_list":["post-100768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza","category-dal-mondo","category-ionio","category-ck10-moda-tendenze","category-provincia","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100768"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100769"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}