{"id":100863,"date":"2018-11-12T14:07:54","date_gmt":"2018-11-12T13:07:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-vela-non-e-solo-regata-tropea-pronta-a-diventare-la-saint-tropez-ditalia\/"},"modified":"2023-01-16T19:02:10","modified_gmt":"2023-01-16T18:02:10","slug":"263818-la-vela-non-e-solo-regata-tropea-pronta-a-diventare-la-saint-tropez-ditalia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/263818-la-vela-non-e-solo-regata-tropea-pronta-a-diventare-la-saint-tropez-ditalia\/","title":{"rendered":"La Vela non \u00e8 solo regata, Tropea pronta a diventare la Saint Tropez d&#8217;Italia"},"content":{"rendered":"<h4>Velisti, armatori e amanti della cucina di qualit\u00e0 animano i week end della &#8216;perla&#8217; del Tirreno. Regata interrotta, grande festa a terra<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>TROPEA (VV) &#8211; Chi pensa che Tropea si addormenti nella stagione autunnale si sbaglia di grosso. Nel fine settimana Tropea il suo porto, il suo mare hanno \u00a0regalato nei due giorni di sole uno spettacolo fantastico in cui si sono succeduti vari momenti di sport e socialit\u00e0. Lo sport Vela che non \u00e8 solo regata. E\u2019 anche conoscenze, incontri, convivialit\u00e0, nuove amicizie e nuovi posti.<strong> La vela d\u2019altura \u00e8 entrata nel Porto di Tropea che con una nuova gestione molto lungimirante far\u00e0 di Tropea la Saint Tropez d\u2019Italia.<\/strong> Sabato 10 novembre nella torretta del porto di Tropea sede del\u00a0 Marina Yacht Club,\u00a0 ritrovo di velisti, armatori e amanti della cucina di alto livello, si \u00e8 svolta la\u00a0 conferenza stampa di\u00a0 presentazione del Campionato Velico d\u2019Altura del Circolo Velico Santa Venere che quest\u2019anno ha abbracciato l\u2019iniziativa del Marina Yacht Club di Tropea\u00a0 con il premio challenger \u00a0\u00a01^ Trofeo Velico Marina Yacht Club di Tropea. E\u2019 stato illustrato anche\u00a0 il \u00a0programma \u00a0delle regate a valere sul\u00a0 Campionato invernale di Vela d\u2019altura del Circolo Velico Santa Venere organizzate dallo stesso \u00a0in collaborazione con il Circolo Velico Lampetia di Cetraro il Yacthing Club di Reggio Calabria e il Club Velico di Tropea.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-263851 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/IMG-20181110-WA0022-440x247.jpg\" alt=\"\" width=\"440\" height=\"247\" title=\"\"><\/p>\n<p>La conferenza stampa ha visto la partecipazione di \u00a0rappresentanti militari, istituzionali e civili i quali hanno certamente con la loro presenza confermato la condivisione e appoggio all\u2019iniziativa sportiva velica e a tutte le persone e strutture che ruotano intorno ad essa. <strong>Pertanto lungo il Tirreno meridionale, da Tropea a Cetraro fino a scendere a Reggio Calabria le acque antistanti i relativi porti saranno colorate anche nelle giornate senza sole dalle n\u00b0 35 fantastiche vele delle rispettive barche.<\/strong>\u00a0Un primo assaggio si \u00e8 avuto ieri nella giornata d\u2019estate di San Martino. In attesa del posizionamento del campo le imbarcazioni provavano il passo, si esercitavano nelle manovre, qualcuno era addirittura in acqua in costume a pulire la carena. Un drone volava costantemente filmando i partecipanti, diversi super yacht erano presenti con spettatori, ma quando ad apertura di regata, il cielo \u00e8 stato colorato tricolore da un ultraleggero\u00a0 cielo \u00e8 stato colorato tricolore da un aeroplano ultraleggero della aviosuperfice Rascaglia di Nicotera si \u00e8 avuta l&#8217;impressione di essere alla Barcolana. La regata \u00e8 partita, prima la classe amatoriale, poi i veterani. Il vento, per\u00f2, \u00e8 andato via via scemando, fino a scomparire del tutto. A meno di met\u00e0 percorso \u00e8 stata interrotta la regata per sopraggiunti limiti di tempo. A mare e a terra comunque la festa c&#8217;\u00e8 stata, regatanti, organizzazione e pubblico si sono congratulati. La prova generale \u00e8 andata bene, gli ingredienti ci sono. Ora si attende il 24 e il 25 per tentare di nuovo l&#8217;avventura, con la speranza che Eolo sia benevolo.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-263823 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/IMG-20181111-WA0143-440x247.jpg\" alt=\"\" width=\"440\" height=\"247\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Velisti, armatori e amanti della cucina di qualit\u00e0 animano i week end della &#8216;perla&#8217; del Tirreno. Regata interrotta, grande festa a terra<\/p>\n","protected":false},"author":22,"featured_media":100864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,34,13,20],"tags":[],"class_list":["post-100863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-magazine","category-qui-green","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100863"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100864"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}