{"id":100922,"date":"2018-11-14T06:04:24","date_gmt":"2018-11-14T05:04:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/elisa-brown-la-voce-piu-soul-della-calabria-presenta-yrros\/"},"modified":"2023-01-16T19:02:15","modified_gmt":"2023-01-16T18:02:15","slug":"264038-elisa-brown-la-voce-piu-soul-della-calabria-presenta-yrros","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/264038-elisa-brown-la-voce-piu-soul-della-calabria-presenta-yrros\/","title":{"rendered":"Elisa Brown, la voce pi\u00f9 soul della Calabria, presenta Yrros"},"content":{"rendered":"<div>\n<h4>Il disco \u00e8 in distribuzione online su tutte le piattaforme digitali.<\/h4>\n<\/div>\n<p><!--more--><\/p>\n<div><\/div>\n<div>COSENZA &#8211; Elisa Brown, definita a pi\u00f9 riprese\u00a0<em>\u201cla voce pi\u00f9 soul della Calabria\u201d<\/em>\u00a0, in occasione del XVII PJF ha presentato al pubblico,\u00a0\u00a0nel magico scenario del cortile del Castello Svevo di Cosenza,\u00a0 il suo primo album ufficiale,\u00a0<strong>\u00a0<\/strong>uscito per la\u00a0\u00a0Picanto Records e realizzato anche grazie ad una borsa di studio assegnatale dall\u2019\u00a0Acep\u00a0\u00a0in occasione dell\u2019ultimo Calabria Jazz Meeting. Il disco, contenente tutti brani inediti scritti a quattro mani con\u00a0Alessio Iorio (fatta eccezione per la cover del brano di Aretha Franklin\u00a0\u00a0<em>\u201cDo Right Woman, Do Right man\u201d<\/em>\u00a0) \u00e8 stato anticipato dall\u2019uscita dello splendido singolo\u00a0<em>\u00a0<a href=\"https:\/\/quicosenza.it\/news\/5708\"> \u201cOh God (OM)\u201d <\/a><\/em>\u00a0che ha letteralmente spopolato su You Tube, facendo registrare quasi 10.000 visualizzazioni.<\/div>\n<div><\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-264043 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/43497180_2085852418131936_8645420333899186176_n-601x400.jpg\" alt=\"\" width=\"601\" height=\"400\" title=\"\"><\/div>\n<p>&nbsp;<\/p>\n<p>Elisa Palermo, in arte Brown, nasce a Cosenza il 6 Giugno del 1982. Inizia a cantare nel coro parrocchiale gi\u00e0 da piccola, finch\u00e8 nel 1998 entra a far parte del gruppo artistico dell\u2019ITC \u201cG.Pezzullo\u201d. Un anno pi\u00f9 tardi diventa la prima voce solista del coro del medesimo istituto, diretto dalla maestra T. Capano, un coro che polifonico che propone anche un repertorio gospel, proprio per la sua particolarit\u00e0 vocale. Nel 2004 interpreta il ruolo dell\u2019operaia Grazia nel Musical M.A.N.(Teatro Rendano) , scritto dal maestro Ivo Scalercio. L\u2019orchestra del musical \u00e8 guidata dal Maestro Cicci Santucci (la tromba di Ennio Morricone), e vede alla sessione ritmica il contrabbassista Giorgio Rosciglione e il batterista Geg\u00e8 Munari, due veterani del jazz italiano. La kermesse di attori vede la partecipazione straordinaria di Jasmine Sannino (voce della colonna sonora del film \u201cLe Fate Ignoranti\u201d) e Gianni Testa, e con la regia di Giovanni Giacobelli. Nello stesso anno inizia a cantare come soprano, contralto e voce solista nel coro Gospel e polifonico\u201dGli 8iClavio &amp; Il Pianoforte\u201d, coro ospite del Cittadella Jazz con Romano Mussolini, e si avvicina al mondo del rock\/blues e della musica leggera italiana collaborando,in occasione di un tour che la vedr\u00e0 impegnata per due anni, con la cover band \u201cSol 20\u201d. Collabora all\u2019incisione dell\u2019Inno del Peperoncino, composto da Ivo Scalercio, per l\u2019Accademia del Peperoncino di Diamante e diventa voce del gruppo Jazz \u201cI Grindelia\u201c. Partecipa ad un gran numero di concorsi classificandosi sempre ai primi posti (\u201cBattisti Day 2003\u201d di San Vincenzo La Costa, \u201cConcorso Mimmo Gaudio 2006\u201d di Mendicino). In particolare il 2006 partecipa alle finali del Premio \u201cMia Martini\u201d di Bagnara Calabra(dir. Art. F. Fasano), presentando il suo primo pezzo inedito ufficiale \u201cSopra un filo\u201c, scritto per lei da G. Vincenzi e F. Silipo; e nel 2008 vince il Tour Music Fest (Mogol,L.Pitteri,F.Fasano, etc) classificandosi prima nella categoria \u201cInterpreti\u201d e aggiudicandosi una borsa di studio con il maestro Luca Pitteri, su oltre 2000 partecipanti provenienti da tutta Italia. Affascinata dal mondo teatrale partecipa a numerose commedie con la \u201cCompagnia Degli Untori\u201d sia come attrice che come cantante, e collabora con il Teatro dell\u2019Acquario\/Centro RAT di Cosenza. Inizia una turn\u00e8 come corista, con la cantante americana Amy Coleman; per la quale scrive nel 2011 , insieme con Alessio Iorio, il brano inedito \u201cGive Me Some Peace\u201d un gospel\/blues, per il progetto \u201cDancing for the Water\u201d, partecipando allo stesso progetto come back vocal e autrice.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-264045 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/46014099_2137882772928900_8024020703122554880_n-400x400.jpg\" alt=\"\" width=\"400\" height=\"400\" title=\"\"><\/p>\n<p>Numerosissime sono le collaborazioni con alcune band del cosentino e le apparizioni nelle reti televisive nazionali e regionali. Nel Maggio 2011, partecipa alla trasmissione \u201cMezzogiorno in Famiglia\u201d su Rai 2 e avr\u00e0 l\u2019onore di esibirsi con l\u2019orchestra del maestro Mazza. Il 2012 \u00e8 l\u2019anno in cui diventa direttrice musicale e artistica del coro \u201c Soul Sighs Gospel Choir\u201d, un coro con pi\u00f9 di 30 elementi, che si \u00e8 esibito negli anni in diversi festival sul territorio, e ha preso parte, nel 2013, al Concerto della Gospel Connection, presso il Parco della Musica di Roma. Un coro ancora oggi attivo, che \u00e8 diventato uno dei cori gospel pi\u00f9 importanti della Calabria. Nello stesso anno registra l\u2019album Bitter Day con la formazione Soul Pains, nel quale partecipa come back vocal in tutti i brani e come solista del brano \u201cI\u2019ll Get My Soul\u201d. Nel 2014 sale sul palco del Blue Note di Milano con le Soul Kiss per accompagnare l\u2019amica Verdiana (Amici 2012) nella presentazione del suo album \u201c Al Centro del Caos\u201d, sullo stesso palco ha la possibilit\u00e0 di esibirsi con il suo brano \u201cCome Back To Love Me\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-264047 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/34962246_1923621751021671_214947028512276480_n-400x400.jpg\" alt=\"\" width=\"400\" height=\"400\" title=\"\"><\/p>\n<p>Scelta tra diversi solisti gospel in Italia, l\u2019 8 Dicembre del 2013, accompagna Edward Taylor come corista \/ solista in occasione del seminario DALLA PAROLA AL CANTO 2013 e a Giugno del 2015 tiene il seminario gospel \u201cThe Power Of Music\u201d, presso l\u2019ICF ROME di Roma con Chris Riccardi e la vocal coach americana Jessica Smith. L\u2019amore per la musica gli ha permesso di salire sul palco, negli anni, con persone del calibro di Joe Amoruso, Rino Zurzolo, Davide Santorsola, Stjepko Gut, Antonella Mazza,Trini Lopez Massie e Rodney Hubbard. Dal 2013 con il suo progetto \u201cElisa Brown Blues Project\u201d \u00e8 protagonista di diversi festival musicali importanti ( Peperoncino Jazz Festival, Divino Jazz, Le colline del Jazz, Festival delle Serre e tanti altri) . Inoltre dallo stesso anno prende parte alla direzione artistica di un noto Seminario Gospel calabrese (Blowing on Soul Gospel Meeting) , che le ha permesso di esibirsi con grandi artisti americani, tra i quali il Grammy Award del Gospel , Vaughan Phoenix, e il noto direttore orchestrale Leon Lacey , quest ultimo si avvale di collaborazioni con Janet Jackson, WyCleaf Jean, Tamela Mann, Donald Lawrence e tanti altri. Nel grande workshop Italiano \u201cGospel Connection\u201d(a cui prende parte da quasi 10 anni) si fa notare da grandi maestri internazionali ed ottiene numerosi consensi da tutti i cori partecipanti. Il 2016 inizia il suo viaggio come operatore olistico della voce e del suono, con grandi maestri che dedicano la loro vita alla ricerca dei suoni ancestrali e del benessere spirituale attraverso il mezzo della voce e del suono (canto armonico, body percussion, circle song); ed inizia un percorso di studi con Albert Hera, Alfredo Biondo e Greta Panettieri. Da Settembre 2016 \u00e8 Vocal Coach con approccio olistico presso diverse scuole d\u2019arte e tiene laboratori collettivi sul Canto dell\u2019Anima in tutta Italia, oltre che incontri individuali per ritrovare la propria voce e attraverso essa ottenere uno stato di benessere e serenit\u00e0. Chiamata come ospite Gospel su diversi palchi italiani a Settembre del 2017 riceve, in occasione del Calabria Jazz Meeting, il prestigioso premio Personaggio dell\u2019Anno \u201cMarco Tamburini\u201d e a Dicembre riceve, dall&#8217;ACEP una borsa di studi per la realizzazione di un album.\u00a0Al momento lavora alla promozione del suo primo album di inediti \u201cYrros\u201d, a cui fa da apripista il singolo &#8220;Oh God (OM)&#8221;, un brano profondo dalle mille sonorit\u00e0 e dalle mille religioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il disco \u00e8 in distribuzione online su tutte le piattaforme digitali.<\/p>\n","protected":false},"author":20,"featured_media":100923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-100922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100922"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100923"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}