{"id":100956,"date":"2018-11-14T14:58:27","date_gmt":"2018-11-14T13:58:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/carlo-tansi-denuncia-violata-la-mia-e-mail-istituzionale\/"},"modified":"2023-01-16T19:02:18","modified_gmt":"2023-01-16T18:02:18","slug":"264161-carlo-tansi-denuncia-violata-la-mia-e-mail-istituzionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/264161-carlo-tansi-denuncia-violata-la-mia-e-mail-istituzionale\/","title":{"rendered":"Carlo Tansi denuncia: &#8220;violata la mia e-mail istituzionale&#8221;"},"content":{"rendered":"<h4>Una grave violazione \u00e8 stata denunciata da Carlo Tansi, geologo e responsabile della protezione civile calabrese. Qualcuno avrebbe violato la sua e-mail istituzionale: &#8220;Forze oscure si oppongono a cambiamento Protezione civile&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8220;Ho appena accertato che <strong>ieri 13 novembre alle 23.32,<\/strong> mentre trascorrevo una serata conviviale con amici in un club service di Cosenza seguita a una mia relazione, qualcuno, violando il mio account di posta elettronica, ha spedito dal mio indirizzo e-mail istituzionale, con modalit\u00e0 che saranno stabilite dalle Autorit\u00e0 competenti, una nota indirizzata a una testata online con la quale manifestavo l&#8217;intenzione, priva di ogni fondamento, di non partecipare alla selezione per dirigente della <strong>Protezione civile della Regione Calabria e di tornare a lavorare al Consiglio Nazionale delle Ricerche&#8221;<\/strong>.<\/p>\n<p>A rendere nota la vicenda \u00e8 proprio Carlo Tansi che sottolinea di avere &#8220;gi\u00e0 preso accordi con i vertici della polizia di Stato &#8211; prosegue Tansi in una nota &#8211; per sporgere immediatamente denuncia in merito a questo grave reato penale perpetrato nei miei confronti. Tutto questo rafforza la mia convinzione che, nell&#8217;imminenza di una mia eventuale riconferma, forze oscure che si oppongono al cambiamento radicale che ho attuato alla guida della Protezione civile regionale, vogliono con tutti i mezzi e con modalit\u00e0 sempre pi\u00f9 criminali ripristinare l&#8217;andazzo di illegalit\u00e0 e gli interessi illegittimi (per svariati milioni di euro annui), che regnavano sovrani prima del mio insediamento. \u00c8 questa la &#8216;ndrangheta dai colletti bianchi che sto iniziando a conoscere sempre pi\u00f9 intimamente&#8221;.<\/p>\n<p>&#8220;Questi <strong>signori del malaffare dal volto oscuro<\/strong> &#8211; conclude Tansi &#8211; possono solo mettersi l&#8217;animo in pace, perch\u00e9 pi\u00f9 continueranno nelle loro sporche azioni e pi\u00f9 io trarr\u00f3 energie sempre pi\u00f9 immense per continuare nella mia giusta azione di adeguamento della Protezione civile alle condizioni di rischio della regione italiana, la Calabria, nettamente pi\u00f9 esposta alle calamit\u00e0 naturali. Se non altro per la sicurezza dei nostri figli&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una grave violazione \u00e8 stata denunciata da Carlo Tansi, geologo e responsabile della protezione civile calabrese. Qualcuno avrebbe violato la sua e-mail istituzionale: &#8220;Forze oscure si oppongono a cambiamento Protezione civile&#8221;<\/p>\n","protected":false},"author":22,"featured_media":100957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-100956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=100956"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/100956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/100957"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=100956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=100956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=100956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}