{"id":10106,"date":"2012-12-20T15:18:04","date_gmt":"2012-12-20T14:18:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=10106"},"modified":"2023-01-17T13:43:15","modified_gmt":"2023-01-17T12:43:15","slug":"4524-immigrati-in-150-bloccano-strada-e-ferrovia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4524-immigrati-in-150-bloccano-strada-e-ferrovia\/","title":{"rendered":"Immigrati: in 150 bloccano strada e ferrovia"},"content":{"rendered":"<p><strong>AMANTEA<\/strong> (Cosenza) &#8211; Circa 150 immigrati inseriti nel progetto &#8220;Nordafrica&#8221; della Protezione Civile hanno attuato oggi una protesta ad Amantea, nel cosentino, dove hanno bloccato la<\/p>\n<p>  <!--more-->  <\/p>\n<p>strada statale 18 tirrenica e la linea ferroviara. Dopo l&#8217;intervento delle forze dell&#8217;ordine, gli immigrati sono stati condotti un una struttura alberghiera che li ospita da circa un anno e mezzo. Qui gli stranieri hanno continuato a protestare, danneggiando la struttura che pertanto e&#8217; circondata da Polizia e Carabinieri. Si tratta dell&#8217;ennesima protesta inscenata dai migranti che ricevono dallo Stato italiano un sussidio giornaliero di 46 euro. Il progetto d&#8217;accoglienza era stato avviato in seguito alla rivolta libica conclusasi con la morte del dittatore Gheddafi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AMANTEA (Cosenza) &#8211; Circa 150 immigrati inseriti nel progetto &#8220;Nordafrica&#8221; della Protezione Civile hanno attuato oggi una protesta ad Amantea, nel cosentino, dove hanno bloccato la<\/p>\n","protected":false},"author":22,"featured_media":10107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-10106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=10106"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/10107"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=10106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=10106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=10106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}